{"id":12825,"date":"2024-06-12T10:19:09","date_gmt":"2024-06-12T10:19:09","guid":{"rendered":"https:\/\/dailyai.com\/?p=12825"},"modified":"2024-06-13T22:25:48","modified_gmt":"2024-06-13T22:25:48","slug":"googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts","status":"publish","type":"post","link":"https:\/\/dailyai.com\/it\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/","title":{"rendered":"La Search Engine Experience (SGE) di Google potrebbe accelerare gli impatti ambientali dell'IA"},"content":{"rendered":"<p><b>L'ultima conferenza I\/O di Google ha visto l'azienda raddoppiare la sua Search Generative Experience (SGE), che incorporer\u00e0 l'intelligenza artificiale generativa in Google Search.\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">SGE, che mira a portare risposte generate dall'intelligenza artificiale a oltre un miliardo di utenti entro la fine del 2024, si basa su Gemini, la famiglia di modelli linguistici di grandi dimensioni (LLM) di Google, per generare risposte simili a quelle umane alle query di ricerca.<\/span><\/p>\n<p>Invece di una ricerca tradizionale su Google, che mostra principalmente i link, vi verr\u00e0 presentato un riepilogo generato dall'intelligenza artificiale insieme ad altri risultati.<\/p>\n<figure id=\"attachment_12844\" aria-describedby=\"caption-attachment-12844\" style=\"width: 836px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12844\" src=\"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/06\/SGE-Bluetooth-Speakers.png-1024x761.webp\" alt=\"SGE\" width=\"836\" height=\"621\" srcset=\"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/06\/SGE-Bluetooth-Speakers.png-1024x761.webp 1024w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/06\/SGE-Bluetooth-Speakers.png-300x223.webp 300w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/06\/SGE-Bluetooth-Speakers.png-768x571.webp 768w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/06\/SGE-Bluetooth-Speakers.png-1536x1141.webp 1536w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/06\/SGE-Bluetooth-Speakers.png-16x12.webp 16w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/06\/SGE-Bluetooth-Speakers.png-60x45.webp 60w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/06\/SGE-Bluetooth-Speakers.png.webp 1750w\" sizes=\"auto, (max-width: 836px) 100vw, 836px\" \/><figcaption id=\"caption-attachment-12844\" class=\"wp-caption-text\">SGE inserisce il testo generato dall'intelligenza artificiale nei risultati di ricerca.<\/figcaption><\/figure>\n<p>Questa \"panoramica sull'intelligenza artificiale\" \u00e8 stata criticata perch\u00e9 <a href=\"https:\/\/dailyai.com\/it\/2024\/05\/google-ai-overview-pythons-are-mammals-and-other-blunders\/\">fornire informazioni senza senso<\/a>e Google sta rapidamente lavorando a soluzioni prima di iniziare il rollout di massa.<\/p>\n<p><span style=\"font-weight: 400;\">Ma oltre a consigliare di aggiungere la colla alla pizza e a dire che i pitoni sono mammiferi, c'\u00e8 un altro problema nella nuova strategia di ricerca guidata dall'intelligenza artificiale di Google: la sua impronta ambientale.\u00a0<\/span><\/p>\n<h2>Perch\u00e9 l'SGE \u00e8 ad alta intensit\u00e0 di risorse<\/h2>\n<p><span style=\"font-weight: 400;\">Mentre i motori di ricerca tradizionali si limitano a recuperare le informazioni esistenti su Internet, i sistemi di intelligenza artificiale generativa come SGE devono creare contenuti completamente nuovi per ogni interrogazione. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questo processo richiede una potenza di calcolo e un'energia molto maggiori rispetto ai metodi di ricerca convenzionali.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si stima che ogni giorno vengano effettuate da 3 a 10 miliardi di ricerche su Google. L'impatto dell'applicazione dell'intelligenza artificiale anche a una piccola percentuale di queste ricerche potrebbe essere incredibile.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sasha Luccioni, ricercatore dell'azienda di AI Hugging Face che studia l'impatto ambientale di queste tecnologie, ha recentemente discusso del forte aumento del consumo energetico che le SGE potrebbero innescare. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Luccioni e il suo team stimano che la generazione di informazioni di ricerca con l'IA potrebbe richiedere 30 volte pi\u00f9 energia di una ricerca convenzionale.<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"\u00c8 logico, no? Mentre una banale query di ricerca trova dati esistenti su Internet, le applicazioni come AI Overviews devono creare informazioni completamente nuove\". <\/span><a href=\"https:\/\/www.scientificamerican.com\/article\/what-do-googles-ai-answers-cost-the-environment\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">ha dichiarato a Scientific American<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nel 2023, Luccioni e i suoi colleghi hanno scoperto che l'addestramento del LLM BLOOM emetteva gas a effetto serra equivalenti a 19 chilogrammi di CO2 per giorno di utilizzo, ovvero la quantit\u00e0 generata dalla guida di 49 miglia con un'auto media a gas. Hanno anche scoperto che la generazione di<\/span><span style=\"font-weight: 400;\">\u00a0due sole immagini utilizzando l'intelligenza artificiale pu\u00f2 consumare tanta energia quanto la ricarica completa di uno smartphone medio.<\/span><\/p>\n<p>Studi precedenti hanno stimato che le emissioni di CO2 associate all'addestramento di un modello di intelligenza artificiale potrebbero superare quelle di centinaia di voli commerciali o di un'automobile media nel corso della sua vita.<\/p>\n<figure id=\"attachment_3418\" aria-describedby=\"caption-attachment-3418\" style=\"width: 798px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3418\" src=\"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/dataconsumption-1024x801.png\" alt=\"Consumo di energia AI\" width=\"798\" height=\"624\" srcset=\"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/dataconsumption-1024x801.png 1024w, https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/dataconsumption-300x235.png 300w, https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/dataconsumption-768x601.png 768w, https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/dataconsumption-370x289.png 370w, https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/dataconsumption-800x626.png 800w, https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/dataconsumption-20x16.png 20w, https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/dataconsumption-740x579.png 740w, https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/dataconsumption-61x48.png 61w, https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/dataconsumption.png 1378w\" sizes=\"auto, (max-width: 798px) 100vw, 798px\" \/><figcaption id=\"caption-attachment-3418\" class=\"wp-caption-text\">Impatto della CO2 sull'addestramento dei modelli di intelligenza artificiale. Fonte: <a href=\"https:\/\/dailyai.com\/it\/2023\/07\/understanding-the-often-overlooked-environmental-impact-of-ai\/\"><span class=\"noTranslate\" data-no-translation=\"\"><span class=\"noTranslate\" data-no-translation=\"\"><span class=\"noTranslate\" data-no-translation=\"\"><span class=\"noTranslate\" data-no-translation=\"\"><span class=\"noTranslate\" data-no-translation=\"\"><span class=\"noTranslate\" data-no-translation=\"\"><span class=\"noTranslate\" data-no-translation=\"\"><span class=\"noTranslate\" data-no-translation=\"\">MIT<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span> Rassegna tecnologica<\/a>.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">In un <\/span><a href=\"https:\/\/www.reuters.com\/technology\/tech-giants-ai-like-bing-bard-poses-billion-dollar-search-problem-2023-02-22\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">intervista rilasciata a Reuters lo scorso anno<\/span><\/a><span style=\"font-weight: 400;\">John Hennessy, presidente della societ\u00e0 madre di Google, Alphabet, ha ammesso lui stesso l'aumento dei costi associati alla ricerca alimentata dall'intelligenza artificiale.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"Uno scambio con un modello linguistico di grandi dimensioni potrebbe costare dieci volte di pi\u00f9 di una ricerca tradizionale\", ha dichiarato, prevedendo per\u00f2 che i costi diminuiranno man mano che i modelli verranno perfezionati.<\/span><\/p>\n<h2>La ricerca AI mette a dura prova infrastrutture e risorse<\/h2>\n<p><span style=\"font-weight: 400;\">Si prevede che i data center che ospitano i server di intelligenza artificiale raddoppieranno il loro consumo energetico entro il 2026, arrivando a consumare potenzialmente tanto quanto <\/span><a href=\"https:\/\/dailyai.com\/it\/2023\/10\/ai-could-consume-the-same-energy-as-the-netherlands-by-2027\/\"><span style=\"font-weight: 400;\">potere come un piccolo paese<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con i produttori di chip come NVIDIA che stanno lanciando chip pi\u00f9 grandi e pi\u00f9 potenti, potrebbe presto prendere il <\/span><a href=\"https:\/\/dailyai.com\/it\/2024\/06\/nvidia-blackwell-by-the-numbers-the-potential-impact-of-nvidias-new-ai-superchip\/\"><span style=\"font-weight: 400;\">equivalente a pi\u00f9 centrali nucleari<\/span><\/a><span style=\"font-weight: 400;\"> per eseguire carichi di lavoro AI su larga scala.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando le aziende che si occupano di AI rispondono alle domande su come questo possa essere sostenuto, in genere citano l'aumento dell'efficienza e della capacit\u00e0 delle fonti rinnovabili e la maggiore efficienza energetica dell'hardware dell'AI.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tuttavia, la transizione verso le fonti di energia rinnovabile per i data center si sta rivelando lenta e complessa.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Come ha spiegato Shaolei Ren, ingegnere informatico dell'Universit\u00e0 della California, Riverside, che studia l'IA sostenibile, \"c'\u00e8 uno squilibrio tra domanda e offerta di energia rinnovabile. La natura intermittente della produzione di energia rinnovabile spesso non \u00e8 all'altezza della potenza costante e stabile richiesta dai data center\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A causa di questo disallineamento, gli impianti a combustibili fossili vengono mantenuti in funzione pi\u00f9 a lungo del previsto nelle aree ad alta concentrazione di infrastrutture tecnologiche.\u00a0<\/span><\/p>\n<p>Un'altra soluzione ai problemi energetici \u00e8 rappresentata dall'hardware AI ad alta efficienza energetica. NVIDIA <a href=\"https:\/\/dailyai.com\/it\/2024\/06\/nvidia-blackwell-by-the-numbers-the-potential-impact-of-nvidias-new-ai-superchip\/\">nuovo chip Blackwell<\/a> \u00e8 molte volte pi\u00f9 efficiente dal punto di vista energetico rispetto ai suoi predecessori, e altre <a href=\"https:\/\/dailyai.com\/it\/2024\/03\/delta-electronics-unveils-energy-efficient-ai-hardware-at-nvidia-gtc\/\">compagnie come Delta<\/a> stanno lavorando su un hardware efficiente per i centri dati.<\/p>\n<p><span style=\"font-weight: 400;\">Rama Ramakrishnan, professore della MIT Sloan School of Management, ha spiegato che mentre il numero di ricerche che passano attraverso gli LLM \u00e8 destinato ad aumentare, il costo per query sembra diminuire man mano che le aziende lavorano per rendere pi\u00f9 efficienti hardware e software.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ma sar\u00e0 sufficiente a compensare la crescente domanda di energia?\u00a0<\/span><span style=\"font-weight: 400;\">\"\u00c8 difficile da prevedere\", afferma Ramakrishnan. \"La mia ipotesi \u00e8 che probabilmente aumenter\u00e0, ma non in modo drammatico\".<\/span><\/p>\n<p>Con l'accelerazione della corsa all'intelligenza artificiale, \u00e8 diventato necessario mitigare l'impatto ambientale. La necessit\u00e0 \u00e8 la madre dell'invenzione e le aziende tecnologiche sono costrette a creare soluzioni per mantenere lo slancio dell'IA.<\/p>\n<p>Hardware efficiente dal punto di vista energetico, energie rinnovabili e <a href=\"https:\/\/dailyai.com\/it\/2024\/02\/nuclear-fusion-and-ai-an-evolving-symbiotic-relationship\/\">anche l'energia da fusione<\/a> pu\u00f2 aprire la strada a un futuro pi\u00f9 sostenibile per l'IA, ma il viaggio \u00e8 pieno di incertezze.<\/p>\n<h2>La SGE potrebbe mettere a dura prova anche le riserve idriche<\/h2>\n<p><span style=\"font-weight: 400;\">Possiamo anche ipotizzare le richieste di acqua create dalla SGE, che potrebbero rispecchiare i grandi aumenti del consumo idrico dei data center attribuiti all'industria dell'IA generativa.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Secondo i recenti rapporti ambientali di Microsoft, il consumo di acqua ha <\/span><a href=\"https:\/\/dailyai.com\/it\/2023\/09\/microsofts-ai-workloads-causes-water-consumption-to-rocket\/\"><span style=\"font-weight: 400;\">\u00e8 aumentato fino a 50%<\/span><\/a><span style=\"font-weight: 400;\"> in alcune regioni, con il consumo idrico del data center di Las Vegas raddoppiato rispetto al 2022. Anche i rapporti di Google hanno registrato un aumento di 20% nella spesa idrica dei data center nel 2023 rispetto al 2022.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ren attribuisce la maggior parte di questa crescita all'IA, affermando: \"\u00c8 giusto dire che la maggior parte della crescita \u00e8 dovuta all'IA, compresi i forti investimenti di Microsoft nell'IA generativa e la partnership con OpenAI\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ren ha stimato che ogni interazione con ChatGPT, composta da 5-50 messaggi, consuma ben 500 ml di acqua.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">In un <\/span><a href=\"https:\/\/arxiv.org\/pdf\/2304.03271\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">carta<\/span><\/a><span style=\"font-weight: 400;\"> pubblicato nel 2023, il team di Ren ha scritto: \"La domanda globale di intelligenza artificiale potrebbe essere responsabile di 4,2-6,6 miliardi di metri cubi di prelievo d'acqua nel 2027, una cifra superiore al prelievo annuale totale di 4-6 Danimarca o della met\u00e0 del Regno Unito\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Utilizzando la ricerca di Ren, possiamo fare alcuni calcoli su come l'SGE di Google potrebbe influire su queste previsioni.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Supponiamo che Google elabori una media di 8,5 miliardi di ricerche giornaliere in tutto il mondo. Supponendo che anche solo una frazione di queste ricerche, ad esempio 10%, utilizzi l'SGE e generi risposte basate sull'intelligenza artificiale con una media di 50 parole per risposta, il consumo di acqua potrebbe essere fenomenale.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Utilizzando la stima di Ren di 500 millilitri di acqua per ogni 5-50 richieste (ad esempio, una singola sessione su Google SGE), possiamo calcolare approssimativamente che 850 milioni di ricerche alimentate da SGE (10% delle ricerche giornaliere di Google) consumerebbero circa 425 milioni di litri di acqua al giorno.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questo equivale alla funzione <em>giornaliero<\/em> consumo idrico di una citt\u00e0 con una popolazione di oltre 2,5 milioni di abitanti.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">In realt\u00e0, il consumo effettivo di acqua pu\u00f2 variare in base a fattori quali l'efficienza dei data center di Google e l'implementazione specifica e la scala dell'SGE. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tuttavia, \u00e8 molto ragionevole ipotizzare che l'SGE e altre forme di ricerca dell'IA aumenteranno ulteriormente l'utilizzo delle risorse dell'IA.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le esperienze globali di intelligenza artificiale come SGE saranno sostenibili su vasta scala? I fattori in gioco sono numerosi, ma non sar\u00e0 una passeggiata.\u00a0\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>L'ultima conferenza I\/O di Google ha visto l'azienda raddoppiare la sua Search Generative Experience (SGE), che incorporer\u00e0 l'intelligenza artificiale generativa in Google Search.  SGE, che mira a portare risposte generate dall'intelligenza artificiale a oltre un miliardo di utenti entro la fine del 2024, si basa su Gemini, la famiglia di modelli linguistici di grandi dimensioni (LLM) di Google, per generare risposte simili a quelle umane alle query di ricerca. Invece di una ricerca tradizionale su Google, che mostra principalmente i link, vi verr\u00e0 presentato un riepilogo generato dall'intelligenza artificiale insieme ad altri risultati. Questa \"panoramica dell'intelligenza artificiale\" \u00e8 stata criticata per il fatto che fornisce informazioni prive di senso, e Google sta rapidamente lavorando per trovare soluzioni prima che inizi la massa.<\/p>","protected":false},"author":2,"featured_media":12826,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[306,102],"class_list":["post-12825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ethics","tag-environment","tag-google"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Google&#039;s Search Engine Experience (SGE) could accelerate AI&#039;s environmental impacts | DailyAI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dailyai.com\/it\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google&#039;s Search Engine Experience (SGE) could accelerate AI&#039;s environmental impacts | DailyAI\" \/>\n<meta property=\"og:description\" content=\"Google\u2019s latest flagship I\/O conference saw the company double down on its Search Generative Experience (SGE) \u2013 which will embed generative AI into Google Search.\u00a0 SGE, which aims to bring AI-generated answers to over a billion users by the end of 2024, relies on Gemini, Google&#8217;s family of large language models (LLMs), to generate human-like responses to search queries. Instead of a traditional Google search, which primarily displays links, you&#8217;ll be presented with an AI-generated summary alongside other results. This &#8220;AI Overview&#8221; has been criticized for providing nonsense information, and Google is fast working on solutions before it begins mass\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dailyai.com\/it\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/\" \/>\n<meta property=\"og:site_name\" content=\"DailyAI\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-12T10:19:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-13T22:25:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/06\/DALL\u00b7E-2024-06-12-11.07.37-A-dark-themed-high-quality-landscape-image-showing-the-environmental-impacts-of-Googles-Search-Engine-Experience-SGE.-Highlight-the-massive-data-.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1792\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Sam Jeans\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DailyAIOfficial\" \/>\n<meta name=\"twitter:site\" content=\"@DailyAIOfficial\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sam Jeans\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\\\/\"},\"author\":{\"name\":\"Sam Jeans\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/person\\\/711e81f945549438e8bbc579efdeb3c9\"},\"headline\":\"Google&#8217;s Search Engine Experience (SGE) could accelerate AI&#8217;s environmental impacts\",\"datePublished\":\"2024-06-12T10:19:09+00:00\",\"dateModified\":\"2024-06-13T22:25:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\\\/\"},\"wordCount\":1161,\"publisher\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/DALL\u00b7E-2024-06-12-11.07.37-A-dark-themed-high-quality-landscape-image-showing-the-environmental-impacts-of-Googles-Search-Engine-Experience-SGE.-Highlight-the-massive-data-.webp\",\"keywords\":[\"environment\",\"Google\"],\"articleSection\":[\"Ethics &amp; Society\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\\\/\",\"url\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\\\/\",\"name\":\"Google's Search Engine Experience (SGE) could accelerate AI's environmental impacts | DailyAI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/DALL\u00b7E-2024-06-12-11.07.37-A-dark-themed-high-quality-landscape-image-showing-the-environmental-impacts-of-Googles-Search-Engine-Experience-SGE.-Highlight-the-massive-data-.webp\",\"datePublished\":\"2024-06-12T10:19:09+00:00\",\"dateModified\":\"2024-06-13T22:25:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/DALL\u00b7E-2024-06-12-11.07.37-A-dark-themed-high-quality-landscape-image-showing-the-environmental-impacts-of-Googles-Search-Engine-Experience-SGE.-Highlight-the-massive-data-.webp\",\"contentUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/DALL\u00b7E-2024-06-12-11.07.37-A-dark-themed-high-quality-landscape-image-showing-the-environmental-impacts-of-Googles-Search-Engine-Experience-SGE.-Highlight-the-massive-data-.webp\",\"width\":1792,\"height\":1024,\"caption\":\"Google SGE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dailyai.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Google&#8217;s Search Engine Experience (SGE) could accelerate AI&#8217;s environmental impacts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#website\",\"url\":\"https:\\\/\\\/dailyai.com\\\/\",\"name\":\"DailyAI\",\"description\":\"Your Daily Dose of AI News\",\"publisher\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dailyai.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#organization\",\"name\":\"DailyAI\",\"url\":\"https:\\\/\\\/dailyai.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Daily-Ai_TL_colour.png\",\"contentUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Daily-Ai_TL_colour.png\",\"width\":4501,\"height\":934,\"caption\":\"DailyAI\"},\"image\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/DailyAIOfficial\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dailyaiofficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@DailyAIOfficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/person\\\/711e81f945549438e8bbc579efdeb3c9\",\"name\":\"Sam Jeans\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g\",\"caption\":\"Sam Jeans\"},\"description\":\"Sam is a science and technology writer who has worked in various AI startups. When he\u2019s not writing, he can be found reading medical journals or digging through boxes of vinyl records.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sam-jeans-6746b9142\\\/\"],\"url\":\"https:\\\/\\\/dailyai.com\\\/it\\\/author\\\/samjeans\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Search Engine Experience (SGE) di Google potrebbe accelerare l'impatto ambientale dell'IA | DailyAI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dailyai.com\/it\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/","og_locale":"it_IT","og_type":"article","og_title":"Google's Search Engine Experience (SGE) could accelerate AI's environmental impacts | DailyAI","og_description":"Google\u2019s latest flagship I\/O conference saw the company double down on its Search Generative Experience (SGE) \u2013 which will embed generative AI into Google Search.\u00a0 SGE, which aims to bring AI-generated answers to over a billion users by the end of 2024, relies on Gemini, Google&#8217;s family of large language models (LLMs), to generate human-like responses to search queries. Instead of a traditional Google search, which primarily displays links, you&#8217;ll be presented with an AI-generated summary alongside other results. This &#8220;AI Overview&#8221; has been criticized for providing nonsense information, and Google is fast working on solutions before it begins mass","og_url":"https:\/\/dailyai.com\/it\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/","og_site_name":"DailyAI","article_published_time":"2024-06-12T10:19:09+00:00","article_modified_time":"2024-06-13T22:25:48+00:00","og_image":[{"width":1792,"height":1024,"url":"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/06\/DALL\u00b7E-2024-06-12-11.07.37-A-dark-themed-high-quality-landscape-image-showing-the-environmental-impacts-of-Googles-Search-Engine-Experience-SGE.-Highlight-the-massive-data-.webp","type":"image\/webp"}],"author":"Sam Jeans","twitter_card":"summary_large_image","twitter_creator":"@DailyAIOfficial","twitter_site":"@DailyAIOfficial","twitter_misc":{"Scritto da":"Sam Jeans","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dailyai.com\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/#article","isPartOf":{"@id":"https:\/\/dailyai.com\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/"},"author":{"name":"Sam Jeans","@id":"https:\/\/dailyai.com\/#\/schema\/person\/711e81f945549438e8bbc579efdeb3c9"},"headline":"Google&#8217;s Search Engine Experience (SGE) could accelerate AI&#8217;s environmental impacts","datePublished":"2024-06-12T10:19:09+00:00","dateModified":"2024-06-13T22:25:48+00:00","mainEntityOfPage":{"@id":"https:\/\/dailyai.com\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/"},"wordCount":1161,"publisher":{"@id":"https:\/\/dailyai.com\/#organization"},"image":{"@id":"https:\/\/dailyai.com\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/#primaryimage"},"thumbnailUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/06\/DALL\u00b7E-2024-06-12-11.07.37-A-dark-themed-high-quality-landscape-image-showing-the-environmental-impacts-of-Googles-Search-Engine-Experience-SGE.-Highlight-the-massive-data-.webp","keywords":["environment","Google"],"articleSection":["Ethics &amp; Society"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/dailyai.com\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/","url":"https:\/\/dailyai.com\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/","name":"La Search Engine Experience (SGE) di Google potrebbe accelerare l'impatto ambientale dell'IA | DailyAI","isPartOf":{"@id":"https:\/\/dailyai.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dailyai.com\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/#primaryimage"},"image":{"@id":"https:\/\/dailyai.com\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/#primaryimage"},"thumbnailUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/06\/DALL\u00b7E-2024-06-12-11.07.37-A-dark-themed-high-quality-landscape-image-showing-the-environmental-impacts-of-Googles-Search-Engine-Experience-SGE.-Highlight-the-massive-data-.webp","datePublished":"2024-06-12T10:19:09+00:00","dateModified":"2024-06-13T22:25:48+00:00","breadcrumb":{"@id":"https:\/\/dailyai.com\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dailyai.com\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dailyai.com\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/#primaryimage","url":"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/06\/DALL\u00b7E-2024-06-12-11.07.37-A-dark-themed-high-quality-landscape-image-showing-the-environmental-impacts-of-Googles-Search-Engine-Experience-SGE.-Highlight-the-massive-data-.webp","contentUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/06\/DALL\u00b7E-2024-06-12-11.07.37-A-dark-themed-high-quality-landscape-image-showing-the-environmental-impacts-of-Googles-Search-Engine-Experience-SGE.-Highlight-the-massive-data-.webp","width":1792,"height":1024,"caption":"Google SGE"},{"@type":"BreadcrumbList","@id":"https:\/\/dailyai.com\/2024\/06\/googles-search-engine-experience-sge-threatens-to-scale-ais-environmental-impacts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dailyai.com\/"},{"@type":"ListItem","position":2,"name":"Google&#8217;s Search Engine Experience (SGE) could accelerate AI&#8217;s environmental impacts"}]},{"@type":"WebSite","@id":"https:\/\/dailyai.com\/#website","url":"https:\/\/dailyai.com\/","name":"DailyAI","description":"La vostra dose quotidiana di notizie sull'intelligenza artificiale","publisher":{"@id":"https:\/\/dailyai.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dailyai.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/dailyai.com\/#organization","name":"DailyAI","url":"https:\/\/dailyai.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/dailyai.com\/#\/schema\/logo\/image\/","url":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/06\/Daily-Ai_TL_colour.png","contentUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/06\/Daily-Ai_TL_colour.png","width":4501,"height":934,"caption":"DailyAI"},"image":{"@id":"https:\/\/dailyai.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/DailyAIOfficial","https:\/\/www.linkedin.com\/company\/dailyaiofficial\/","https:\/\/www.youtube.com\/@DailyAIOfficial"]},{"@type":"Person","@id":"https:\/\/dailyai.com\/#\/schema\/person\/711e81f945549438e8bbc579efdeb3c9","name":"Sam Jeans","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g","caption":"Sam Jeans"},"description":"Sam \u00e8 uno scrittore di scienza e tecnologia che ha lavorato in diverse startup di intelligenza artificiale. Quando non scrive, lo si pu\u00f2 trovare a leggere riviste mediche o a scavare tra scatole di dischi in vinile.","sameAs":["https:\/\/www.linkedin.com\/in\/sam-jeans-6746b9142\/"],"url":"https:\/\/dailyai.com\/it\/author\/samjeans\/"}]}},"_links":{"self":[{"href":"https:\/\/dailyai.com\/it\/wp-json\/wp\/v2\/posts\/12825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyai.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyai.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyai.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyai.com\/it\/wp-json\/wp\/v2\/comments?post=12825"}],"version-history":[{"count":7,"href":"https:\/\/dailyai.com\/it\/wp-json\/wp\/v2\/posts\/12825\/revisions"}],"predecessor-version":[{"id":12893,"href":"https:\/\/dailyai.com\/it\/wp-json\/wp\/v2\/posts\/12825\/revisions\/12893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailyai.com\/it\/wp-json\/wp\/v2\/media\/12826"}],"wp:attachment":[{"href":"https:\/\/dailyai.com\/it\/wp-json\/wp\/v2\/media?parent=12825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyai.com\/it\/wp-json\/wp\/v2\/categories?post=12825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyai.com\/it\/wp-json\/wp\/v2\/tags?post=12825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}