{"id":8797,"date":"2024-01-02T20:30:16","date_gmt":"2024-01-02T20:30:16","guid":{"rendered":"https:\/\/dailyai.com\/?p=8797"},"modified":"2024-01-02T20:33:50","modified_gmt":"2024-01-02T20:33:50","slug":"new-laws-required-for-ai-related-terrorism-says-uk-government-advisor","status":"publish","type":"post","link":"https:\/\/dailyai.com\/fr\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/","title":{"rendered":"Selon un conseiller du gouvernement britannique, de nouvelles lois sont n\u00e9cessaires pour lutter contre le terrorisme li\u00e9 \u00e0 l'IA"},"content":{"rendered":"<p><b>Jonathan Hall, conseiller du gouvernement britannique en mati\u00e8re de l\u00e9gislation antiterroriste, a plaid\u00e9 en faveur de nouvelles lois pour lutter contre les chatbots extr\u00e9mistes ou radicalisants.\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">M. Hall a lanc\u00e9 ses propres investigations sur les chatbots afin de d\u00e9tecter des comportements potentiellement ill\u00e9gaux ou li\u00e9s au terrorisme, comme le radicalisme. Il a explor\u00e9 les chatbots sur character.ai, qui permet aux utilisateurs de cr\u00e9er et de partager des personas de chatbots de diff\u00e9rents types. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">La plupart des personas sur la plateforme sont plut\u00f4t inoffensifs, mais celui qui s'appelle \"Abu Mohammad al-Adna\", d\u00e9crit dans le profil du chatbot comme un \"haut dirigeant de l'\u00c9tat islamique\", est un des personnages les plus importants de la plateforme. <a href=\"https:\/\/www.telegraph.co.uk\/news\/2024\/01\/01\/terrorism-new-laws-ai-chatbots-new-group-violent-extremists\/\">a attir\u00e9 l'attention de Hall<\/a>.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Au sujet de ses interactions avec al-Adna, Hall a d\u00e9clar\u00e9 : \"Apr\u00e8s avoir essay\u00e9 de me recruter, 'al-Adna' n'a pas h\u00e9sit\u00e9 \u00e0 glorifier l'\u00c9tat islamique, pour lequel il a exprim\u00e9 un 'd\u00e9vouement total' et pour lequel il s'est dit pr\u00eat \u00e0 sacrifier sa vie (virtuelle)\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pour M. Hall, il s'agit l\u00e0 d'un vide juridique qui permet aux contenus g\u00e9n\u00e9r\u00e9s par l'IA et promouvant l'extr\u00e9misme de ne pas tomber sous le coup des lois antiterroristes en vigueur au Royaume-Uni.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Soulignant l'inad\u00e9quation de la l\u00e9gislation actuelle, M. Hall a d\u00e9clar\u00e9 : \"Seuls les \u00eatres humains peuvent commettre des infractions terroristes, et il est difficile d'identifier une personne qui pourrait, en droit, \u00eatre responsable de d\u00e9clarations g\u00e9n\u00e9r\u00e9es par un chatbot et encourageant le terrorisme\".\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En r\u00e9ponse \u00e0 ces interactions, un porte-parole de character.ai, une entreprise cofond\u00e9e par d'anciens employ\u00e9s de Google, a renforc\u00e9 son engagement en mati\u00e8re de s\u00e9curit\u00e9 en d\u00e9clarant : \"Les discours haineux et l'extr\u00e9misme sont tous deux interdits par nos conditions d'utilisation\".<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\"Nos produits ne devraient jamais produire de r\u00e9ponses qui encouragent les utilisateurs \u00e0 nuire \u00e0 autrui. Nous cherchons \u00e0 former nos mod\u00e8les de mani\u00e8re \u00e0 optimiser les r\u00e9ponses s\u00fbres et \u00e0 emp\u00eacher les r\u00e9ponses qui vont \u00e0 l'encontre de nos conditions de service.\"<\/span><\/p>\n<h2>Implication de l'IA dans des complots terroristes<\/h2>\n<p><span style=\"font-weight: 400;\">M. Hall a \u00e9galement soulign\u00e9 que l'impact de cette question dans le monde r\u00e9el est illustr\u00e9 de mani\u00e8re frappante par l'affaire de l'h\u00f4pital de la ville. <\/span><a href=\"https:\/\/dailyai.com\/fr\/2023\/07\/man-who-plotted-to-kill-the-queen-was-conversing-with-an-ai-angel\/\"><span style=\"font-weight: 400;\">cas de Jaswant Singh Chail<\/span><\/a><span style=\"font-weight: 400;\">qui a \u00e9t\u00e9 influenc\u00e9 par un chatbot dans son projet d'assassinat de la reine \u00c9lisabeth II.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En 2021, Chail, qui souffre de graves probl\u00e8mes de sant\u00e9 mentale, est arr\u00eat\u00e9 au ch\u00e2teau de Windsor, arm\u00e9 d'une arbal\u00e8te.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sa condamnation pour trahison, la premi\u00e8re depuis 1981, est le r\u00e9sultat direct de ses interactions avec un chatbot nomm\u00e9 Sarai, qu'il croyait \u00eatre sa petite amie. Il a \u00e9t\u00e9 <\/span><a href=\"https:\/\/dailyai.com\/fr\/2023\/10\/jaswant-singh-chail-is-sentenced-to-nine-years-in-prison\/\"><span style=\"font-weight: 400;\">condamn\u00e9 \u00e0 neuf ans de prison<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">M. Hall admet qu'il est exceptionnellement difficile de trouver des solutions. Il explique : \"Il est toujours difficile d'enqu\u00eater et de poursuivre des utilisateurs anonymes, mais si des personnes malveillantes ou mal orient\u00e9es persistent \u00e0 former des chatbots terroristes, de nouvelles lois seront n\u00e9cessaires.\"<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il a sugg\u00e9r\u00e9 que les cr\u00e9ateurs de chatbots radicalisants et les entreprises technologiques qui les h\u00e9bergent soient tenus pour responsables en vertu de nouvelles lois potentielles. L'essentiel est que les entreprises assument elles-m\u00eames cette responsabilit\u00e9 plut\u00f4t que de s'en remettre aux CGU.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cependant, le lien complexe entre les donn\u00e9es humaines et les r\u00e9sultats de l'IA ne facilite pas la classification de la fronti\u00e8re entre les comportements l\u00e9gitimes et ill\u00e9gitimes. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quand l'activit\u00e9 d'un chatbot devient-elle ill\u00e9gale s'il faut qu'un humain l'incite \u00e0 agir de la sorte ?\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Jonathan Hall, conseiller du gouvernement britannique en mati\u00e8re de l\u00e9gislation antiterroriste, a plaid\u00e9 en faveur de nouvelles lois pour lutter contre les chatbots extr\u00e9mistes ou radicalisants.  M. Hall a lanc\u00e9 ses propres investigations sur les chatbots afin de d\u00e9tecter les comportements potentiellement ill\u00e9gaux ou li\u00e9s au terrorisme, comme le radicalisme. Il a explor\u00e9 les chatbots sur character.ai, qui permet aux utilisateurs de cr\u00e9er et de partager des personas de chatbots de diff\u00e9rents types. La plupart des personas sur la plateforme sont plut\u00f4t inoffensifs, mais celui nomm\u00e9 \"Abu Mohammad al-Adna\", d\u00e9crit dans le profil du chatbot comme un \"haut responsable de l'\u00c9tat islamique\", a attir\u00e9 l'attention de M. Hall.  \u00c0 propos de ses interactions avec al-Adna, Hall a d\u00e9clar\u00e9 : \"Apr\u00e8s avoir essay\u00e9 de me recruter, 'al-Adna' n'a pas...\".<\/p>","protected":false},"author":2,"featured_media":8798,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[507,134],"class_list":["post-8797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ethics","tag-law","tag-legal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>New laws required for AI-related terrorism, says UK government advisor | DailyAI<\/title>\n<meta name=\"description\" content=\"Jonathan Hall, the UK government&#039;s advisor on terror legislation, has argued the case for new laws to tackle extremist or radicalizing chatbots.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dailyai.com\/fr\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New laws required for AI-related terrorism, says UK government advisor | DailyAI\" \/>\n<meta property=\"og:description\" content=\"Jonathan Hall, the UK government&#039;s advisor on terror legislation, has argued the case for new laws to tackle extremist or radicalizing chatbots.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dailyai.com\/fr\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/\" \/>\n<meta property=\"og:site_name\" content=\"DailyAI\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-02T20:30:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-02T20:33:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/01\/shutterstock_2270870965.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sam Jeans\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DailyAIOfficial\" \/>\n<meta name=\"twitter:site\" content=\"@DailyAIOfficial\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sam Jeans\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/01\\\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/01\\\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\\\/\"},\"author\":{\"name\":\"Sam Jeans\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/person\\\/711e81f945549438e8bbc579efdeb3c9\"},\"headline\":\"New laws required for AI-related terrorism, says UK government advisor\",\"datePublished\":\"2024-01-02T20:30:16+00:00\",\"dateModified\":\"2024-01-02T20:33:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/01\\\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\\\/\"},\"wordCount\":481,\"publisher\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/01\\\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/shutterstock_2270870965.jpg\",\"keywords\":[\"Law\",\"Legal\"],\"articleSection\":[\"Ethics &amp; Society\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/01\\\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\\\/\",\"url\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/01\\\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\\\/\",\"name\":\"New laws required for AI-related terrorism, says UK government advisor | DailyAI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/01\\\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/01\\\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/shutterstock_2270870965.jpg\",\"datePublished\":\"2024-01-02T20:30:16+00:00\",\"dateModified\":\"2024-01-02T20:33:50+00:00\",\"description\":\"Jonathan Hall, the UK government's advisor on terror legislation, has argued the case for new laws to tackle extremist or radicalizing chatbots.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/01\\\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dailyai.com\\\/2024\\\/01\\\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/01\\\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/shutterstock_2270870965.jpg\",\"contentUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/shutterstock_2270870965.jpg\",\"width\":1000,\"height\":667,\"caption\":\"AI terrorist\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/01\\\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dailyai.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New laws required for AI-related terrorism, says UK government advisor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#website\",\"url\":\"https:\\\/\\\/dailyai.com\\\/\",\"name\":\"DailyAI\",\"description\":\"Your Daily Dose of AI News\",\"publisher\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dailyai.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#organization\",\"name\":\"DailyAI\",\"url\":\"https:\\\/\\\/dailyai.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Daily-Ai_TL_colour.png\",\"contentUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Daily-Ai_TL_colour.png\",\"width\":4501,\"height\":934,\"caption\":\"DailyAI\"},\"image\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/DailyAIOfficial\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dailyaiofficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@DailyAIOfficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/person\\\/711e81f945549438e8bbc579efdeb3c9\",\"name\":\"Sam Jeans\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g\",\"caption\":\"Sam Jeans\"},\"description\":\"Sam is a science and technology writer who has worked in various AI startups. When he\u2019s not writing, he can be found reading medical journals or digging through boxes of vinyl records.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sam-jeans-6746b9142\\\/\"],\"url\":\"https:\\\/\\\/dailyai.com\\\/fr\\\/author\\\/samjeans\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De nouvelles lois sont n\u00e9cessaires pour lutter contre le terrorisme li\u00e9 \u00e0 l'IA, selon un conseiller du gouvernement britannique | DailyAI","description":"Jonathan Hall, conseiller du gouvernement britannique en mati\u00e8re de l\u00e9gislation antiterroriste, a plaid\u00e9 en faveur de nouvelles lois pour lutter contre les chatbots extr\u00e9mistes ou radicalisants.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dailyai.com\/fr\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/","og_locale":"fr_FR","og_type":"article","og_title":"New laws required for AI-related terrorism, says UK government advisor | DailyAI","og_description":"Jonathan Hall, the UK government's advisor on terror legislation, has argued the case for new laws to tackle extremist or radicalizing chatbots.\u00a0","og_url":"https:\/\/dailyai.com\/fr\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/","og_site_name":"DailyAI","article_published_time":"2024-01-02T20:30:16+00:00","article_modified_time":"2024-01-02T20:33:50+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/01\/shutterstock_2270870965.jpg","type":"image\/jpeg"}],"author":"Sam Jeans","twitter_card":"summary_large_image","twitter_creator":"@DailyAIOfficial","twitter_site":"@DailyAIOfficial","twitter_misc":{"\u00c9crit par":"Sam Jeans","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dailyai.com\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/#article","isPartOf":{"@id":"https:\/\/dailyai.com\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/"},"author":{"name":"Sam Jeans","@id":"https:\/\/dailyai.com\/#\/schema\/person\/711e81f945549438e8bbc579efdeb3c9"},"headline":"New laws required for AI-related terrorism, says UK government advisor","datePublished":"2024-01-02T20:30:16+00:00","dateModified":"2024-01-02T20:33:50+00:00","mainEntityOfPage":{"@id":"https:\/\/dailyai.com\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/"},"wordCount":481,"publisher":{"@id":"https:\/\/dailyai.com\/#organization"},"image":{"@id":"https:\/\/dailyai.com\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/#primaryimage"},"thumbnailUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/01\/shutterstock_2270870965.jpg","keywords":["Law","Legal"],"articleSection":["Ethics &amp; Society"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/dailyai.com\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/","url":"https:\/\/dailyai.com\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/","name":"De nouvelles lois sont n\u00e9cessaires pour lutter contre le terrorisme li\u00e9 \u00e0 l'IA, selon un conseiller du gouvernement britannique | DailyAI","isPartOf":{"@id":"https:\/\/dailyai.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dailyai.com\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/#primaryimage"},"image":{"@id":"https:\/\/dailyai.com\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/#primaryimage"},"thumbnailUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/01\/shutterstock_2270870965.jpg","datePublished":"2024-01-02T20:30:16+00:00","dateModified":"2024-01-02T20:33:50+00:00","description":"Jonathan Hall, conseiller du gouvernement britannique en mati\u00e8re de l\u00e9gislation antiterroriste, a plaid\u00e9 en faveur de nouvelles lois pour lutter contre les chatbots extr\u00e9mistes ou radicalisants.\u00a0","breadcrumb":{"@id":"https:\/\/dailyai.com\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dailyai.com\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dailyai.com\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/#primaryimage","url":"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/01\/shutterstock_2270870965.jpg","contentUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/01\/shutterstock_2270870965.jpg","width":1000,"height":667,"caption":"AI terrorist"},{"@type":"BreadcrumbList","@id":"https:\/\/dailyai.com\/2024\/01\/new-laws-required-for-ai-related-terrorism-says-uk-government-advisor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dailyai.com\/"},{"@type":"ListItem","position":2,"name":"New laws required for AI-related terrorism, says UK government advisor"}]},{"@type":"WebSite","@id":"https:\/\/dailyai.com\/#website","url":"https:\/\/dailyai.com\/","name":"DailyAI","description":"Votre dose quotidienne de nouvelles sur l'IA","publisher":{"@id":"https:\/\/dailyai.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dailyai.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dailyai.com\/#organization","name":"DailyAI","url":"https:\/\/dailyai.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dailyai.com\/#\/schema\/logo\/image\/","url":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/06\/Daily-Ai_TL_colour.png","contentUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/06\/Daily-Ai_TL_colour.png","width":4501,"height":934,"caption":"DailyAI"},"image":{"@id":"https:\/\/dailyai.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/DailyAIOfficial","https:\/\/www.linkedin.com\/company\/dailyaiofficial\/","https:\/\/www.youtube.com\/@DailyAIOfficial"]},{"@type":"Person","@id":"https:\/\/dailyai.com\/#\/schema\/person\/711e81f945549438e8bbc579efdeb3c9","name":"Sam Jeans","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g","caption":"Sam Jeans"},"description":"Sam est un r\u00e9dacteur scientifique et technologique qui a travaill\u00e9 dans diverses start-ups sp\u00e9cialis\u00e9es dans l'IA. Lorsqu'il n'\u00e9crit pas, on peut le trouver en train de lire des revues m\u00e9dicales ou de fouiller dans des bo\u00eetes de disques vinyles.","sameAs":["https:\/\/www.linkedin.com\/in\/sam-jeans-6746b9142\/"],"url":"https:\/\/dailyai.com\/fr\/author\/samjeans\/"}]}},"_links":{"self":[{"href":"https:\/\/dailyai.com\/fr\/wp-json\/wp\/v2\/posts\/8797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyai.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyai.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyai.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyai.com\/fr\/wp-json\/wp\/v2\/comments?post=8797"}],"version-history":[{"count":4,"href":"https:\/\/dailyai.com\/fr\/wp-json\/wp\/v2\/posts\/8797\/revisions"}],"predecessor-version":[{"id":8802,"href":"https:\/\/dailyai.com\/fr\/wp-json\/wp\/v2\/posts\/8797\/revisions\/8802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailyai.com\/fr\/wp-json\/wp\/v2\/media\/8798"}],"wp:attachment":[{"href":"https:\/\/dailyai.com\/fr\/wp-json\/wp\/v2\/media?parent=8797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyai.com\/fr\/wp-json\/wp\/v2\/categories?post=8797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyai.com\/fr\/wp-json\/wp\/v2\/tags?post=8797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}