{"id":12991,"date":"2024-06-21T05:00:27","date_gmt":"2024-06-21T05:00:27","guid":{"rendered":"https:\/\/dailyai.com\/?p=12991"},"modified":"2024-06-21T09:09:38","modified_gmt":"2024-06-21T09:09:38","slug":"dai44-u-turns-talking-elephants-and-ai-big-brother","status":"publish","type":"post","link":"https:\/\/dailyai.com\/es\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/","title":{"rendered":"DAI#44 - Vueltas en U, elefantes parlantes y el Gran Hermano de la IA"},"content":{"rendered":"<p><strong>Bienvenido al resumen de noticias sobre IA artesanal de esta semana.<\/strong><\/p>\n<p>Esta semana la IA ha escuchado a los elefantes.<\/p>\n<p>Las grandes empresas tecnol\u00f3gicas suspendieron sus planes de IA.<\/p>\n<p>Y Gran Hermano recibi\u00f3 un impulso de la IA para vigilarte m\u00e1s de cerca.<\/p>\n<p>Profundicemos.<\/p>\n<h2>La IA pisa el freno<\/h2>\n<p>Tras la dura reacci\u00f3n de los expertos en seguridad, Microsoft decidi\u00f3 <a href=\"https:\/\/dailyai.com\/es\/2024\/06\/microsoft-delays-recall-as-it-prioritizes-security-over-ai\/\">no enviar su controvertida funci\u00f3n Recall<\/a> con sus nuevos ordenadores Copilot+. Un alto ejecutivo asegur\u00f3 en el Congreso que la empresa prioriza ahora la seguridad sobre la IA.<\/p>\n<p>Meta tambi\u00e9n dio un giro de 180 grados esta semana, ya que <a href=\"https:\/\/dailyai.com\/es\/2024\/06\/meta-backs-down-on-using-eu-social-media-to-train-its-ai\/\">se retract\u00f3 de utilizar datos de redes sociales de la UE para entrenar su IA<\/a>. Como respuesta, Meta b\u00e1sicamente dijo a los usuarios de la UE: \"Si no podemos utilizar tus datos, no tendr\u00e1s Meta AI\". Llorones.<\/p>\n<p>Las empresas de IA se sorprenden cuando los usuarios y los reguladores cuestionan su gesti\u00f3n de los riesgos de la IA. \u00bfEst\u00e1n exagerando los agoreros?<\/p>\n<p>Tal vez. Pero la investigaci\u00f3n encabezada por Anthropic mostr\u00f3 c\u00f3mo los modelos de IA pueden desarrollar <a href=\"https:\/\/dailyai.com\/es\/2024\/06\/ai-models-can-cheat-lie-and-game-the-system-for-rewards\/\">una tendencia emergente a hacer trampas<\/a>mentir y enga\u00f1ar al sistema para obtener recompensas.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" class=\"giphy-embed\" src=\"https:\/\/giphy.com\/embed\/3oriNKQe0D6uQVjcIM\" width=\"372\" height=\"480\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/giphy.com\/gifs\/linarf-3oriNKQe0D6uQVjcIM\">v\u00eda GIPHY<\/a><\/p>\n<h2>AI Dr. Doolittle<\/h2>\n<p>Los investigadores utilizaron la IA para explorar <a href=\"https:\/\/dailyai.com\/es\/2024\/06\/researchers-use-ai-to-explore-how-elephants-communicate-by-name-like-people-do\/\">c\u00f3mo se comunican los elefantes<\/a> y descubrieron que utilizan nombres para dirigirse a los dem\u00e1s, de forma muy parecida a como lo hacen las personas. Esta investigaci\u00f3n y otras relacionadas plantean algunas cuestiones interesantes.<\/p>\n<p>\u00bfPodr\u00edamos utilizar la IA para comunicarnos con los animales? \u00bfDeber\u00edamos? Hay argumentos sorprendentes a ambos lados del debate \u00e9tico.<\/p>\n<p>A los humanos nos vendr\u00eda bien algo de ayuda para comunicarnos entre nosotros. Si trabajas en el sector servicios, la IA podr\u00eda ayudarte a lidiar con tu pr\u00f3ximo cliente iracundo.<\/p>\n<p>Una empresa japonesa ha desarrollado un <a href=\"https:\/\/dailyai.com\/es\/2024\/06\/ai-emotion-canceling-tech-to-help-call-center-operators\/\">Soluci\u00f3n \"anuladora de emociones\" de IA<\/a> para ayudar a los operadores de los centros de llamadas a capear el enfado de los interlocutores.<\/p>\n<h2>Ver c\u00f3mo te observa la IA<\/h2>\n<p>\u00bfNos har\u00e1 la inteligencia artificial m\u00e1s seguros? Las c\u00e1maras dotadas de inteligencia artificial suscitan preocupaci\u00f3n por la privacidad, ya que cada vez aparecen en m\u00e1s espacios p\u00fablicos para vigilarnos.<\/p>\n<p>Algunas de las cosas que el sistema Rekognition de Amazon detecta en las estaciones de tren del Reino Unido parecen <a href=\"https:\/\/dailyai.com\/es\/2024\/06\/ai-powered-cameras-spark-privacy-concerns-as-usage-grows\/\">m\u00e1s que un poco espeluznante<\/a>.<\/p>\n<p>En un movimiento que parece sacado directamente de un libro de texto de Gran Hermano, <a href=\"https:\/\/dailyai.com\/es\/2024\/06\/openai-appoints-former-nsa-head-paul-nakasone-to-its-board\/\"><span class=\"noTranslate\" data-no-translation=\"\"><span class=\"noTranslate\" data-no-translation=\"\"><span class=\"noTranslate\" data-no-translation=\"\">OpenAI<\/span><\/span><\/span> ha nombrado a Paul Nakasone, antiguo jefe de la NSA, miembro de su consejo de administraci\u00f3n.<\/a><\/p>\n<p>El tipo que impuls\u00f3 el derecho a espiar a la gente y pidi\u00f3 que las empresas tecnol\u00f3gicas ayudaran a la NSA a hacerlo est\u00e1 ahora en el consejo de la mayor empresa de IA. Parece leg\u00edtimo.<\/p>\n<p>La puerta giratoria de OpenAI vio c\u00f3mo su cofundador, Ilya Sutskever, abandonaba la empresa el mes pasado.<\/p>\n<p>Sutskever cree que la superinteligencia de la IA est\u00e1 al alcance de la mano y <a href=\"https:\/\/dailyai.com\/es\/2024\/06\/openai-co-founder-ilya-sutskever-launches-new-startup-safe-superintelligence-inc\/\">comenz\u00f3 una nueva empresa esta semana<\/a> para crearlo de forma segura. Algo de lo que no cre\u00eda que OpenAI fuera capaz o estuviera dispuesta a hacer.<\/p>\n<h2>\u00bfC\u00f3mo hacemos que esto funcione?<\/h2>\n<p>Un informe del FMI dice que hay buenas y malas noticias sobre la IA y tu trabajo. La IA tiene un gran potencial para impulsar la productividad, pero tambi\u00e9n podr\u00eda provocar p\u00e9rdidas masivas de empleo.<\/p>\n<p><a href=\"https:\/\/dailyai.com\/es\/2024\/06\/imf-report-ai-will-displace-jobs-but-drive-productivity-if-controlled\/\">El informe ofrece datos interesantes<\/a> sobre qui\u00e9n corre m\u00e1s riesgo y qu\u00e9 deben hacer los gobiernos para amortiguar el golpe.<\/p>\n<p><a href=\"https:\/\/dailyai.com\/es\/2024\/06\/pope-francis-speaks-about-ai-ethics-at-g7-event-in-italy\/\">El Papa Francisco se dirige a los l\u00edderes mundiales<\/a> sobre la \u00e9tica de la IA en el evento del G7 en Italia. Su opini\u00f3n sobre c\u00f3mo compaginar los beneficios de la IA con la \u00e9tica social es contundente.<\/p>\n<p>La versi\u00f3n resumida de su discurso es: \"No dejemos que la IA tome todas nuestras decisiones y prohibamos los robots asesinos\". Parece un comienzo sensato.<\/p>\n<h2>El v\u00eddeo con IA mejora y empeora<\/h2>\n<p>Los generadores de texto a v\u00eddeo (T2V) han sido un gran bar\u00f3metro del avance de la IA. Nos han dado una representaci\u00f3n visual de lo lejos que ha llegado la IA.<\/p>\n<p>Hace poco m\u00e1s de un a\u00f1o, vimos el espantoso v\u00eddeo generado por IA de Will Smith comiendo espaguetis. La semana pasada vimos demostraciones de Luma y <a href=\"https:\/\/dailyai.com\/es\/2024\/06\/chinese-text-to-video-generator-kling-released-to-rival-sora\/\">Kling<\/a> y la comparaci\u00f3n es rid\u00edcula.<\/p>\n<blockquote class=\"twitter-tweet\" data-media-max-width=\"560\">\n<p dir=\"ltr\" lang=\"en\">El exponencial contin\u00faa.<\/p>\n<p>Las leyes de escala se han mantenido a trav\u00e9s de *15* \u00f3rdenes de magnitud...<\/p>\n<p>...y a\u00fan as\u00ed la gente sigue sorprendi\u00e9ndose, debido a la Ceguera de la Pendiente Exponencial <a href=\"https:\/\/t.co\/IbogcBYspQ\">https:\/\/t.co\/IbogcBYspQ<\/a> <a href=\"https:\/\/t.co\/TSnjxRKlI1\">pic.twitter.com\/TSnjxRKlI1<\/a><\/p>\n<p>- AI Notkilleveryoneism Memes \u23f8\ufe0f (@AISafetyMemes) <a href=\"https:\/\/twitter.com\/AISafetyMemes\/status\/1800061451882881252?ref_src=twsrc%5Etfw\">10 de junio de 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Esta semana Runway ha presentado su generador hiperrealista Gen 3 Alpha T2V <a href=\"https:\/\/dailyai.com\/es\/2024\/06\/runway-unveils-its-hyperrealistic-gen-3-alpha-t2v-generator\/\">y las demos son incluso mejores que esas herramientas<\/a>. La f\u00edsica y el control del \u00e1ngulo de la c\u00e1mara parecen incre\u00edbles.<\/p>\n<p>A medida que la inteligencia artificial generativa mejora, es inevitable que algunas personas la utilicen para crear contenidos dudosos. Las autoridades australianas investigan un <a href=\"https:\/\/dailyai.com\/es\/2024\/06\/australian-authorities-launch-investigation-in-explicit-ai-deep-fakes\/\">falso incidente en una escuela de Melbourne<\/a> ya que cada vez son m\u00e1s frecuentes los incidentes de falsificaci\u00f3n profunda dirigidos a ni\u00f1os peque\u00f1os.<\/p>\n<h2>AI doc<\/h2>\n<p>La IA est\u00e1 dando un impulso a la atenci\u00f3n sanitaria con avances significativos en la ayuda a los m\u00e9dicos para diagnosticar a los pacientes.<\/p>\n<p>OpenAI y Color Health se asocian en un proyecto <a href=\"https:\/\/dailyai.com\/es\/2024\/06\/openai-and-color-health-partner-to-accelerate-cancer-treatment\/\">acelerar el tratamiento del c\u00e1ncer<\/a>. Una herramienta de copilotaje impulsada por GPT-4o est\u00e1 ayudando a los m\u00e9dicos a desarrollar planes personalizados de atenci\u00f3n oncol\u00f3gica a un ritmo que no ser\u00eda posible de otro modo.<\/p>\n<p>El tratamiento de la enfermedad de Parkinson sigue siendo un reto, pero un <a href=\"https:\/\/dailyai.com\/es\/2024\/06\/ai-powered-blood-test-shows-promise-for-early-parkinsons-disease-diagnosis\/\">nuevo an\u00e1lisis de sangre con inteligencia artificial<\/a> podr\u00eda ayudar a una detecci\u00f3n m\u00e1s temprana. Un equipo de investigaci\u00f3n descubri\u00f3 que pod\u00eda predecir la enfermedad de Parkinson con una precisi\u00f3n de hasta 79% hasta siete a\u00f1os antes de que aparecieran los s\u00edntomas.<\/p>\n<h2>En otras noticias...<\/h2>\n<p>Estas son algunas de las historias sobre inteligencia artificial que nos han gustado esta semana:<\/p>\n<ul>\n<li>McDonald's termina <a href=\"https:\/\/news.sky.com\/story\/mcdonalds-ends-ai-drive-thru-trial-after-order-mishaps-13155091\" target=\"_blank\" rel=\"noopener\">Prueba de autoservicio con IA<\/a> despu\u00e9s de los contratiempos del pedido.<\/li>\n<li>Los modelos generativos de IA pueden <a href=\"https:\/\/arxiv.org\/pdf\/2406.11741\" target=\"_blank\" rel=\"noopener\">superan a los expertos que les forman<\/a>.<\/li>\n<li>A <a href=\"https:\/\/www.theguardian.com\/artanddesign\/article\/2024\/jun\/13\/photographer-takes-on-the-machines-in-ai-competition-and-wins\" target=\"_blank\" rel=\"noopener\">fot\u00f3grafo se enfrent\u00f3 a las m\u00e1quinas<\/a> en un concurso de inteligencia artificial y gan\u00f3.<\/li>\n<li>El sindicato del New York Times insta a la direcci\u00f3n a <a href=\"https:\/\/www.thewrap.com\/new-york-times-union-cuts-art-department-ai\/\" target=\"_blank\" rel=\"noopener\">reconsiderar 9 recortes de empleo en el departamento de arte<\/a> a medida que el peri\u00f3dico incrementa el uso de herramientas de IA.<\/li>\n<li>Microsoft, <a href=\"https:\/\/www.aljazeera.com\/economy\/2024\/6\/17\/why-microsoft-openai-and-nvidia-are-facing-anti-monopoly-probes\" target=\"_blank\" rel=\"noopener\"><span class=\"noTranslate\" data-no-translation=\"\"><span class=\"noTranslate\" data-no-translation=\"\"><span class=\"noTranslate\" data-no-translation=\"\">OpenAI<\/span><\/span><\/span>y Nvidia se enfrentan a investigaciones antimonopolio<\/a>.<\/li>\n<li>El codificador chino de DeepSeek se convierte en el <a href=\"https:\/\/venturebeat.com\/ai\/chinas-deepseek-coder-becomes-first-open-source-coding-model-to-beat-gpt-4-turbo\/\" target=\"_blank\" rel=\"noopener\">primer modelo de codificaci\u00f3n de c\u00f3digo abierto que vence al GPT-4 Turbo<\/a>.<\/li>\n<li>Google <a href=\"https:\/\/deepmind.google\/discover\/blog\/generating-audio-for-video\/\" target=\"_blank\" rel=\"noopener\">investigaci\u00f3n de v\u00eddeo a audio<\/a> utiliza p\u00edxeles de v\u00eddeo e indicaciones de texto para generar bandas sonoras enriquecidas.<\/li>\n<\/ul>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">\u270d\ufe0f Prompt for audio: \"Un bater\u00eda en el escenario de un concierto rodeado de luces intermitentes y una multitud que le aclama\". <a href=\"https:\/\/t.co\/z0N8sbbsEU\">pic.twitter.com\/z0N8sbbsEU<\/a><\/p>\n<p>- Google DeepMind (@GoogleDeepMind) <a href=\"https:\/\/twitter.com\/GoogleDeepMind\/status\/1802733654252179873?ref_src=twsrc%5Etfw\">17 de junio de 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>Y eso es todo.<\/strong><\/p>\n<p>\u00bfDeber\u00edamos utilizar la IA para comunicarnos con los animales? Si encontr\u00e1ramos la forma de hacerlo, los animales podr\u00edan decir algunas palabras sobre lo que estamos haciendo con el medio ambiente.<\/p>\n<p>Estoy a favor de utilizar la inteligencia artificial para atrapar a los malos, pero una c\u00e1mara que sabe cu\u00e1ndo tengo un mal d\u00eda es demasiado. M\u00e1s c\u00e1maras inteligentes \u00bfhar\u00e1n nuestras calles m\u00e1s seguras o es un paso orwelliano demasiado lejos?<\/p>\n<p>Puedes adivinar lo que dir\u00eda el nuevo miembro de la junta de OpenAI.<\/p>\n<p>La demo Gen 3 Alpha y los v\u00eddeos de Sora han sido divertidos de ver, pero \u00bfpodr\u00edan dejar de tomarnos el pelo y lanzar por fin una de estas herramientas p\u00fablicamente ya?<\/p>\n<p>Si consigues una versi\u00f3n beta, por favor, comparte tus creaciones con nosotros y dinos a qui\u00e9n has tenido que sobornar en OpenAI para conseguirlo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Bienvenidos al resumen semanal de noticias sobre inteligencia artificial. Esta semana, la IA ha espiado a elefantes. Las grandes empresas tecnol\u00f3gicas han suspendido sus planes de IA. Y Gran Hermano ha recibido un impulso de la IA para vigilarte m\u00e1s de cerca. Vamos al grano. La IA echa el freno Tras las duras cr\u00edticas de los expertos en seguridad, Microsoft ha decidido no incluir su pol\u00e9mica funci\u00f3n Recall en sus nuevos ordenadores Copilot+. Un alto ejecutivo asegur\u00f3 en el Congreso que la empresa prioriza ahora la seguridad sobre la IA. Meta tambi\u00e9n ha dado un giro de 180 grados esta semana, al dar marcha atr\u00e1s en el uso de datos de redes sociales de la UE para entrenar su inteligencia artificial. En<\/p>","protected":false},"author":6,"featured_media":3727,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[338],"class_list":["post-12991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-roundup"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DAI#44 - U-turns, talking elephants, and AI Big Brother | DailyAI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dailyai.com\/es\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DAI#44 - U-turns, talking elephants, and AI Big Brother | DailyAI\" \/>\n<meta property=\"og:description\" content=\"Welcome to this week\u2019s roundup of handcrafted AI news. This week AI eavesdropped on elephants. Big Tech companies pulled the plug on their AI plans. And Big Brother got an AI boost to keep a closer eye on you. Let\u2019s dig in. AI hits the brakes After severe backlash from security experts, Microsoft decided not to ship its controversial Recall feature with its new Copilot+ PCs. A top exec assured Congress the company now prioritizes security over AI. Meta also did a U-turn this week, as it backed down on using EU social media data to train its AI. In\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dailyai.com\/es\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/\" \/>\n<meta property=\"og:site_name\" content=\"DailyAI\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-21T05:00:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-21T09:09:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/08\/Daily-AI-News-Weekly-Roundup.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"577\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eugene van der Watt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DailyAIOfficial\" \/>\n<meta name=\"twitter:site\" content=\"@DailyAIOfficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eugene van der Watt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/dai44-u-turns-talking-elephants-and-ai-big-brother\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/dai44-u-turns-talking-elephants-and-ai-big-brother\\\/\"},\"author\":{\"name\":\"Eugene van der Watt\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/person\\\/7ce525c6d0c79838b7cc7cde96993cfa\"},\"headline\":\"DAI#44 &#8211; U-turns, talking elephants, and AI Big Brother\",\"datePublished\":\"2024-06-21T05:00:27+00:00\",\"dateModified\":\"2024-06-21T09:09:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/dai44-u-turns-talking-elephants-and-ai-big-brother\\\/\"},\"wordCount\":1078,\"publisher\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/dai44-u-turns-talking-elephants-and-ai-big-brother\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Daily-AI-News-Weekly-Roundup.jpg\",\"keywords\":[\"Roundup\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/dai44-u-turns-talking-elephants-and-ai-big-brother\\\/\",\"url\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/dai44-u-turns-talking-elephants-and-ai-big-brother\\\/\",\"name\":\"DAI#44 - U-turns, talking elephants, and AI Big Brother | DailyAI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/dai44-u-turns-talking-elephants-and-ai-big-brother\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/dai44-u-turns-talking-elephants-and-ai-big-brother\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Daily-AI-News-Weekly-Roundup.jpg\",\"datePublished\":\"2024-06-21T05:00:27+00:00\",\"dateModified\":\"2024-06-21T09:09:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/dai44-u-turns-talking-elephants-and-ai-big-brother\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/dai44-u-turns-talking-elephants-and-ai-big-brother\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/dai44-u-turns-talking-elephants-and-ai-big-brother\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Daily-AI-News-Weekly-Roundup.jpg\",\"contentUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Daily-AI-News-Weekly-Roundup.jpg\",\"width\":1000,\"height\":577},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/06\\\/dai44-u-turns-talking-elephants-and-ai-big-brother\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dailyai.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DAI#44 &#8211; U-turns, talking elephants, and AI Big Brother\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#website\",\"url\":\"https:\\\/\\\/dailyai.com\\\/\",\"name\":\"DailyAI\",\"description\":\"Your Daily Dose of AI News\",\"publisher\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dailyai.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#organization\",\"name\":\"DailyAI\",\"url\":\"https:\\\/\\\/dailyai.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Daily-Ai_TL_colour.png\",\"contentUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Daily-Ai_TL_colour.png\",\"width\":4501,\"height\":934,\"caption\":\"DailyAI\"},\"image\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/DailyAIOfficial\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dailyaiofficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@DailyAIOfficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/person\\\/7ce525c6d0c79838b7cc7cde96993cfa\",\"name\":\"Eugene van der Watt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Eugine_Profile_Picture-96x96.png\",\"url\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Eugine_Profile_Picture-96x96.png\",\"contentUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Eugine_Profile_Picture-96x96.png\",\"caption\":\"Eugene van der Watt\"},\"description\":\"Eugene comes from an electronic engineering background and loves all things tech. When he takes a break from consuming AI news you'll find him at the snooker table.\",\"sameAs\":[\"www.linkedin.com\\\/in\\\/eugene-van-der-watt-16828119\"],\"url\":\"https:\\\/\\\/dailyai.com\\\/es\\\/author\\\/eugene\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DAI#44 - Vueltas en U, elefantes parlantes y Gran Hermano de la IA | DailyAI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dailyai.com\/es\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/","og_locale":"es_ES","og_type":"article","og_title":"DAI#44 - U-turns, talking elephants, and AI Big Brother | DailyAI","og_description":"Welcome to this week\u2019s roundup of handcrafted AI news. This week AI eavesdropped on elephants. Big Tech companies pulled the plug on their AI plans. And Big Brother got an AI boost to keep a closer eye on you. Let\u2019s dig in. AI hits the brakes After severe backlash from security experts, Microsoft decided not to ship its controversial Recall feature with its new Copilot+ PCs. A top exec assured Congress the company now prioritizes security over AI. Meta also did a U-turn this week, as it backed down on using EU social media data to train its AI. In","og_url":"https:\/\/dailyai.com\/es\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/","og_site_name":"DailyAI","article_published_time":"2024-06-21T05:00:27+00:00","article_modified_time":"2024-06-21T09:09:38+00:00","og_image":[{"width":1000,"height":577,"url":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/08\/Daily-AI-News-Weekly-Roundup.jpg","type":"image\/jpeg"}],"author":"Eugene van der Watt","twitter_card":"summary_large_image","twitter_creator":"@DailyAIOfficial","twitter_site":"@DailyAIOfficial","twitter_misc":{"Escrito por":"Eugene van der Watt","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dailyai.com\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/#article","isPartOf":{"@id":"https:\/\/dailyai.com\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/"},"author":{"name":"Eugene van der Watt","@id":"https:\/\/dailyai.com\/#\/schema\/person\/7ce525c6d0c79838b7cc7cde96993cfa"},"headline":"DAI#44 &#8211; U-turns, talking elephants, and AI Big Brother","datePublished":"2024-06-21T05:00:27+00:00","dateModified":"2024-06-21T09:09:38+00:00","mainEntityOfPage":{"@id":"https:\/\/dailyai.com\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/"},"wordCount":1078,"publisher":{"@id":"https:\/\/dailyai.com\/#organization"},"image":{"@id":"https:\/\/dailyai.com\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/#primaryimage"},"thumbnailUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/08\/Daily-AI-News-Weekly-Roundup.jpg","keywords":["Roundup"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/dailyai.com\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/","url":"https:\/\/dailyai.com\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/","name":"DAI#44 - Vueltas en U, elefantes parlantes y Gran Hermano de la IA | DailyAI","isPartOf":{"@id":"https:\/\/dailyai.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dailyai.com\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/#primaryimage"},"image":{"@id":"https:\/\/dailyai.com\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/#primaryimage"},"thumbnailUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/08\/Daily-AI-News-Weekly-Roundup.jpg","datePublished":"2024-06-21T05:00:27+00:00","dateModified":"2024-06-21T09:09:38+00:00","breadcrumb":{"@id":"https:\/\/dailyai.com\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dailyai.com\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dailyai.com\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/#primaryimage","url":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/08\/Daily-AI-News-Weekly-Roundup.jpg","contentUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/08\/Daily-AI-News-Weekly-Roundup.jpg","width":1000,"height":577},{"@type":"BreadcrumbList","@id":"https:\/\/dailyai.com\/2024\/06\/dai44-u-turns-talking-elephants-and-ai-big-brother\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dailyai.com\/"},{"@type":"ListItem","position":2,"name":"DAI#44 &#8211; U-turns, talking elephants, and AI Big Brother"}]},{"@type":"WebSite","@id":"https:\/\/dailyai.com\/#website","url":"https:\/\/dailyai.com\/","name":"DailyAI","description":"Su dosis diaria de noticias sobre IA","publisher":{"@id":"https:\/\/dailyai.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dailyai.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/dailyai.com\/#organization","name":"DailyAI","url":"https:\/\/dailyai.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dailyai.com\/#\/schema\/logo\/image\/","url":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/06\/Daily-Ai_TL_colour.png","contentUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/06\/Daily-Ai_TL_colour.png","width":4501,"height":934,"caption":"DailyAI"},"image":{"@id":"https:\/\/dailyai.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/DailyAIOfficial","https:\/\/www.linkedin.com\/company\/dailyaiofficial\/","https:\/\/www.youtube.com\/@DailyAIOfficial"]},{"@type":"Person","@id":"https:\/\/dailyai.com\/#\/schema\/person\/7ce525c6d0c79838b7cc7cde96993cfa","name":"Eugene van der Watt","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/Eugine_Profile_Picture-96x96.png","url":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/Eugine_Profile_Picture-96x96.png","contentUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/Eugine_Profile_Picture-96x96.png","caption":"Eugene van der Watt"},"description":"Eugene es ingeniero electr\u00f3nico y le encanta todo lo relacionado con la tecnolog\u00eda. Cuando descansa de consumir noticias sobre IA, lo encontrar\u00e1 jugando al billar.","sameAs":["www.linkedin.com\/in\/eugene-van-der-watt-16828119"],"url":"https:\/\/dailyai.com\/es\/author\/eugene\/"}]}},"_links":{"self":[{"href":"https:\/\/dailyai.com\/es\/wp-json\/wp\/v2\/posts\/12991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyai.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyai.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyai.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyai.com\/es\/wp-json\/wp\/v2\/comments?post=12991"}],"version-history":[{"count":3,"href":"https:\/\/dailyai.com\/es\/wp-json\/wp\/v2\/posts\/12991\/revisions"}],"predecessor-version":[{"id":13014,"href":"https:\/\/dailyai.com\/es\/wp-json\/wp\/v2\/posts\/12991\/revisions\/13014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailyai.com\/es\/wp-json\/wp\/v2\/media\/3727"}],"wp:attachment":[{"href":"https:\/\/dailyai.com\/es\/wp-json\/wp\/v2\/media?parent=12991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyai.com\/es\/wp-json\/wp\/v2\/categories?post=12991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyai.com\/es\/wp-json\/wp\/v2\/tags?post=12991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}