{"id":6840,"date":"2023-10-27T09:21:03","date_gmt":"2023-10-27T09:21:03","guid":{"rendered":"https:\/\/dailyai.com\/?p=6840"},"modified":"2024-03-27T23:33:07","modified_gmt":"2024-03-27T23:33:07","slug":"dai10-woodpeckers-robocalls-and-poisoned-ai-data","status":"publish","type":"post","link":"https:\/\/dailyai.com\/de\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/","title":{"rendered":"DAI#10 - Spechte, Robocalls und vergiftete AI-Daten"},"content":{"rendered":"<p>Willkommen zu den Nachrichten dieser Woche, die speziell f\u00fcr KI-Fans zusammengestellt wurden, die nicht auf Silizium basieren.<\/p>\n<p>Diese Woche hat AI einen B\u00fcrgermeister dazu gebracht, in Zungen zu sprechen.<\/p>\n<p>Ein zweit\u00e4giges Gipfeltreffen und $10m hoffen auf eine L\u00f6sung f\u00fcr die KI-Sicherheit.<\/p>\n<p>Und ChatGPT wird alles tun, was Sie verlangen, wenn Sie ihm die richtigen Bilder zeigen.<\/p>\n<h2>Rufen Sie uns nicht an, AI wird Sie anrufen<\/h2>\n<p>Wenn Sie schon dachten, dass Robo-Anrufe schlecht sind, dann stellen Sie sich vor, wie sie mit einer Prise KI sein k\u00f6nnten. <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/fcc-to-investigate-ais-impact-on-robocalls\/\">Die FCC versucht, eine L\u00f6sung zu finden<\/a> was man dagegen tun kann.<\/p>\n<p>Unterdessen hat der B\u00fcrgermeister von New York City gerade <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/nyc-mayor-uses-deep-fakes-of-his-voice-to-robocall-residents\/\">deepfake tech to robocall city residents<\/a> in einer Reihe von Sprachen, die er nicht spricht. Endlich b\u00fcrokratische Effizienz oder einfach nur unheimlich?<\/p>\n<p>Die Polizei von Idaho macht die Menschen dort \"sicherer\" durch den Einsatz von <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/idaho-police-force-invests-in-ai-powered-remote-phone-access-tech\/\">KI-Technologie zum Entsperren und Abrufen von Daten aus Ihrem Telefon<\/a> aus der Ferne. Sie sagen nicht genau, wie es funktioniert, aber sie schw\u00f6ren, dass es legal ist.<\/p>\n<p>Der Einsatz von KI im \u00f6ffentlichen Sektor sollte die Warteschlangen verk\u00fcrzen und den Menschen den Zugang zu Dienstleistungen erleichtern. Beweise f\u00fcr <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/evidence-of-ai-misuse-unearthed-in-the-uk-public-sector\/\">KI-Missbrauch, Voreingenommenheit und Dysfunktionalit\u00e4t im britischen \u00f6ffentlichen Sektor<\/a> ist die Spitze des Eisbergs.<\/p>\n<p>AI: \"Ich sehe hier, dass Sie Bulgare sind. Sie m\u00fcssen einen Betrug begehen. Abgelehnt!'<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" class=\"giphy-embed\" src=\"https:\/\/giphy.com\/embed\/JliGmPEIgzGLe\" width=\"480\" height=\"268\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/giphy.com\/gifs\/computer-computers-problems-JliGmPEIgzGLe\">\u00fcber GIPHY<\/a><\/p>\n<p>Die britische Regierung hat die <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/uk-government-releases-schedule-for-the-ai-safety-summit\/\">Zeitplan f\u00fcr den AI-Sicherheitsgipfel<\/a> die am 1. und 2. November stattfinden wird.<\/p>\n<p>Sie haben auch einen Bericht ver\u00f6ffentlicht, der als Diskussionsgrundlage f\u00fcr den zweit\u00e4gigen Gipfel dienen wird. Der Bericht listet auf <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/uk-report-lists-potential-ai-risks-and-doomsday-scenarios\/\">potenzielle KI-Risiken und Weltuntergangsszenarien<\/a> die man von Verschw\u00f6rungstheoretikern am Rande der Gesellschaft erwarten w\u00fcrde, so dass es einem die Augen \u00f6ffnet, wenn man sie in einem Regierungsdokument findet.<\/p>\n<p>Um ihren Beitrag zu diesem Zweck zu leisten, haben die gro\u00dfen KI-Unternehmen die <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/big-tech-ai-companies-launch-10-million-ai-safety-fund\/\">AI-Sicherheitsfonds<\/a> und hat eine Runde gedreht, um $10 Millionen in die Kasse zu bekommen.<\/p>\n<p>Der CEO von DeepMind sagte, dass <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/deepminds-ceo-draws-comparison-between-ai-risks-and-the-climate-crisis\/\">AI-Risiken sind mit der Klimakrise vergleichbar<\/a>. Unter Bezugnahme auf die Kernschmelze in Tschernobyl sagte er: \"Wir wissen noch nicht, wie eine 'KI-Katastrophe' aussehen k\u00f6nnte\".<\/p>\n<p>Ein zweit\u00e4giger Gipfel und $10m ist die Ameise auf dem Gleis, die versucht, den KI-G\u00fcterzug zu stoppen.<\/p>\n<h2>Zeig mir das Geld<\/h2>\n<p>Die Technologiebranche hat einige gro\u00dfartige KI-Produkte entwickelt, aber <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/can-the-tech-industry-overcome-the-challenge-of-ai-monetization\/\">k\u00f6nnen sie tats\u00e4chlich Geld verdienen<\/a> von ihnen? Die Kosten, die der Betrieb von ChatGPT oder Co-Pilot jeden Tag verursacht, sind atemberaubend.<\/p>\n<p>Die Investoren sind offensichtlich der Meinung, dass sich damit Geld verdienen l\u00e4sst. Apple hat gerade seine j\u00e4hrliche <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/apple-increases-investment-in-generative-ai-to-1-billion-yearly\/\">Investitionen in generative KI auf $1 Milliarde<\/a> und versucht, nach einem langsamen Start im KI-Rennen aufzuholen.<\/p>\n<p>Das neue iPhone ist im Vergleich zu den anderen iPhones mit KI-Funktionen etwas sp\u00e4rlich ausgestattet. <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/googles-pixel-8-phones-incorporate-advanced-ai-image-editing-features\/\">Googles Pixel 8 Telefone<\/a>die mit fortschrittlichen AI-Bildbearbeitungsfunktionen ausgestattet sind.<\/p>\n<p>Haben Sie in Nvidia investiert, bevor sich der Aktienkurs im letzten Jahr vervierfacht hat? Wenn Sie mit einer Party in einer Airbnb-Unterkunft feiern wollen, dann <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/airbnb-uses-ai-to-wage-war-on-house-parties\/\">Die k\u00fcnstliche Intelligenz k\u00f6nnte diesen Pl\u00e4nen einen Strich durch die Rechnung machen.<\/a><\/p>\n<h2>Mehr Modi, mehr Probleme<\/h2>\n<p>Die multimodalen und generativen KI-F\u00e4higkeiten verbessern sich weiterhin exponentiell. KI kann jetzt eine <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/3d-gpt-generates-3d-environments-from-text-prompts\/\">3D-Umgebung anhand einer einfachen Textaufforderung<\/a>aber es wird auch verwendet, um <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/deep-fake-images-of-child-sex-abuse-rising-says-new-report\/\">gef\u00e4lschte Bilder von sexuellem Kindesmissbrauch<\/a>.<\/p>\n<p>Die Bildverarbeitungsfunktion des GPT-4 leistet Erstaunliches bei der Bildanalyse, aber diese F\u00e4higkeit macht es auch anf\u00e4llig f\u00fcr Angriffe. Wenn es um das Jailbreaking des Modells geht, <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/gpt-4s-multimodal-capability-makes-it-vulnerable-to-attack\/\">ein Bild sagt wirklich mehr als tausend Worte<\/a>.<\/p>\n<p>Sind Sie ein K\u00fcnstler oder Fotograf, der es satt hat, dass KI-Modelle seine Arbeit abrei\u00dfen? Nun, jetzt k\u00f6nnen Sie eine <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/data-poisoning-tool-helps-artists-punish-ai-scrapers\/\">Datenvergiftungstool namens Nightshade<\/a> um KI-Bildgeneratoren zu verwirren.<\/p>\n<p>Es hat seinen Anteil an Herausforderungen, aber GPT-4V ist wirklich erstaunlich. Schauen Sie sich dieses Beispiel an und sagen Sie mir dann noch einmal, warum ChatGPT das n\u00e4chste Wort so gut vorhersagen kann.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/i.ibb.co\/ypbCkCF\/Zombo-Droid-22102023092445.jpg\" width=\"640\" height=\"1072\" \/><\/p>\n<h2>KI im Grenzbereich<\/h2>\n<p>Der Betrieb gr\u00f6\u00dferer KI-Modelle auf batteriebetriebenen Ger\u00e4ten k\u00f6nnte schneller m\u00f6glich sein, als man denkt. IBM k\u00fcndigte seinen Prototyp <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/ibm-northpole-chip-promises-faster-low-energy-ai-processing\/\">NorthPole-Chip<\/a> die eine viel schnellere und energiesparende KI-Verarbeitung verspricht. Der neuartige Ansatz des Unternehmens f\u00fcr die Chip-Architektur k\u00f6nnte einen Wendepunkt darstellen.<\/p>\n<p>Der Einsatz von k\u00fcnstlicher Intelligenz im Grenzbereich wird unseren zuk\u00fcnftigen Robotern einen gro\u00dfen Schub geben. Meta k\u00fcndigte Habitat 3.0 an, ein <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/meta-announces-the-ai-robot-training-platform-habitat-3-0\/\">AI-Roboter-Trainingsplattform<\/a> das Robotern beibringt, wie sie im Haushalt helfen k\u00f6nnen, und zwar Tausende Male schneller als beim Training in der realen Welt.<\/p>\n<h2>M\u00f6gen die Sp\u00e4ne fallen, wie sie wollen<\/h2>\n<p>Obwohl sie eigentlich erst im November in Kraft treten sollte, k\u00fcndigte die US-Regierung an, dass ihre <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/new-us-ai-hardware-export-bans-to-come-into-effect-immediately\/\">Exportverbote f\u00fcr KI-Hardware<\/a> sollen sofort in Kraft treten. Es ist damit zu rechnen, dass der Schwarzmarkthandel mit Nvidia-Chips weitergehen wird.<\/p>\n<p>China hat sich mit KI-Chips eingedeckt und steckt viel Geld in die KI-Entwicklung. Ein chinesisches Start-up namens Zhipu hat sich eine Finanzierung in H\u00f6he von 2,5 Milliarden Yuan ($340 Millionen) gesichert. Es gibt <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/chinese-startup-zhipu-secures-2-5-billion-yuan-340-million-funding\/\">einige \u00fcberraschende Namen unter seinen Investoren<\/a>.<\/p>\n<p>Hat ChatGPT irgendetwas erfunden, als Sie es baten, ein Bild zu beschreiben? Die chinesische Forschung k\u00f6nnte helfen, das Problem der Halluzinationen zu l\u00f6sen. <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/woodpecker-could-solve-multimodal-llm-hallucinations\/\">Woodpecker ist ein erstaunlich einfaches<\/a> eine Open-Source-L\u00f6sung, die multimodale Modelle wie GPT-4V erheblich verbessern k\u00f6nnte.<\/p>\n<h2>KI beschleunigt die Forschung<\/h2>\n<p>Forschungsarbeiten m\u00fcssen von Fachkollegen begutachtet werden, aber die Leute, die das tun, sind oft zu sehr damit besch\u00e4ftigt, ihre eigenen Arbeiten zu schreiben. <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/chatgpt-shows-strengths-in-emulating-the-peer-review-process\/\">ChatGPT ist erstaunlich gut<\/a> um die Arbeit eines anderen Menschen zu erledigen.<\/p>\n<p>KI hilft auch \u00c4rzten, schnell herauszufinden, was mit Ihnen los ist. Forscher waren in der Lage zu nutzen <a href=\"https:\/\/dailyai.com\/de\/2023\/10\/researchers-diagnose-diabetes-in-seconds-using-voice-recordings\/\">KI zur Diagnose von Diabetes<\/a> durch die Analyse einer 6- bis 10-sek\u00fcndigen Sprachaufnahme eines Patienten.<\/p>\n<p>All die gro\u00dfartigen Dinge, die KI-Modelle leisten k\u00f6nnen, werden durch Daten angetrieben. Neue Untersuchungen von KI-Datens\u00e4tzen zeigen<a href=\"https:\/\/dailyai.com\/de\/2023\/10\/new-research-into-datasets-reveals-systemic-ethical-and-legal-issues\/\">ystemische, ethische und rechtliche Fragen<\/a> die die Kehrseite der KI-M\u00fcnze sind.<\/p>\n<h2>Weitere Nachrichten...<\/h2>\n<p>In dieser Woche gab es viele weitere klickw\u00fcrdige KI-Nachrichten. Hier sind einige unserer Favoriten:<\/p>\n<ul>\n<li>John Stewarts Show auf Apple TV wurde abgesetzt wegen <a href=\"https:\/\/www.theverge.com\/2023\/10\/19\/23924549\/jon-stewart-apple-ai-china-cancel\" target=\"_blank\" rel=\"noopener\">seine Kommentare zu AI und China<\/a>.<\/li>\n<li>LLMs sind erstaunlich schlecht in Mathe. Diese Forscher nahmen Llama 2 und machten <a href=\"https:\/\/venturebeat.com\/ai\/meet-llemma-the-math-focused-open-source-ai-that-outperforms-rivals\/\" target=\"_blank\" rel=\"noopener\">LLEMMA, ein auf Mathematik fokussierter LLM<\/a>.<\/li>\n<li>Wir warten alle auf die Ver\u00f6ffentlichung von GPT-5, aber <a href=\"https:\/\/the-decoder.com\/bill-gates-does-not-expect-gpt-5-to-be-much-better-than-gpt-4\/\" target=\"_blank\" rel=\"noopener\">Bill Gates sagt<\/a> wird es nicht viel besser sein als GPT-4. Haben Sie einen Hauch von OpenAI Neid dort Bill?<\/li>\n<\/ul>\n<ul>\n<li>KI ist nicht gut f\u00fcr die Umwelt, aber sie kann lustige Deepfakes von Umweltaktivisten machen.<\/li>\n<\/ul>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\" style=\"text-align: center;\">Das Verr\u00fcckte ist, dass die KI im Moment so schlecht ist wie nie zuvor... \ud83e\udd28<a href=\"https:\/\/twitter.com\/hashtag\/HowDareYou?src=hash&amp;ref_src=twsrc%5Etfw\">#HowDareYou<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/GretaThunberg?src=hash&amp;ref_src=twsrc%5Etfw\">#GretaThunberg<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/AI?src=hash&amp;ref_src=twsrc%5Etfw\">#AI<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/edited?src=hash&amp;ref_src=twsrc%5Etfw\">1TP5Bearbeitet<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/ClimateCrisis?src=hash&amp;ref_src=twsrc%5Etfw\">1TP5Klimakrise<\/a> <a href=\"https:\/\/t.co\/mkEz25E0gp\">pic.twitter.com\/mkEz25E0gp<\/a><\/p>\n<p style=\"text-align: center;\">- Mrgunsngear (@Mrgunsngear) <a href=\"https:\/\/twitter.com\/Mrgunsngear\/status\/1716564798366798228?ref_src=twsrc%5Etfw\">23. Oktober 2023<\/a><\/p>\n<\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Und das war's dann auch schon.<\/p>\n<p>Wenn Sie in NYC leben, w\u00fcrden wir gerne wissen, ob Sie einen Anruf vom B\u00fcrgermeister erhalten haben und wie er sich angeh\u00f6rt hat.<\/p>\n<p>W\u00e4re es f\u00fcr Sie in Ordnung, wenn ein KI-Roboter Ihre Hausarbeit erledigen w\u00fcrde? Oder werden Sie mit dem Kauf noch warten, bis der KI-Sicherheitsgipfel einen Weg gefunden hat, um zu verhindern, dass wir aus Versehen Skynet bauen?<\/p>\n<p>Wenn ich $75k \u00fcbrig h\u00e4tte, w\u00fcrde ich das Risiko eingehen und eine <a href=\"https:\/\/bostondynamics.com\/products\/spot\/\" target=\"_blank\" rel=\"noopener\">Boston Dynamics-Werbespot<\/a> robodog.<\/p>\n<p>Wenn Sie der Meinung sind, dass wir eine gro\u00dfartige AI-Neuigkeit verpasst haben, lassen Sie es uns bitte wissen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Willkommen zu den Nachrichten dieser Woche, die speziell f\u00fcr Nicht-Silikon-Fans von KI zusammengestellt wurden. Diese Woche brachte KI einen B\u00fcrgermeister dazu, in fremden Zungen zu sprechen. Ein zweit\u00e4giges Gipfeltreffen und $10m hoffen auf eine L\u00f6sung f\u00fcr die KI-Sicherheit. Und: ChatGPT tut alles, was Sie verlangen, wenn Sie ihm die richtigen Bilder zeigen. Rufen Sie nicht uns an, sondern die KI wird Sie anrufen Wenn Sie Robo-Anrufe bisher f\u00fcr schlimm hielten, stellen Sie sich vor, wie sie mit einer Prise KI sein k\u00f6nnten. Die FCC versucht herauszufinden, was man dagegen tun kann. In der Zwischenzeit hat der B\u00fcrgermeister von New York City eine Deepfake-Technologie eingesetzt, um die Einwohner der Stadt per Roboteranruf zu erreichen.<\/p>","protected":false},"author":6,"featured_media":3727,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[338],"class_list":["post-6840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industry","tag-roundup"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DAI#10 - Woodpeckers, Robocalls, and poisoned AI data | DailyAI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dailyai.com\/de\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DAI#10 - Woodpeckers, Robocalls, and poisoned AI data | DailyAI\" \/>\n<meta property=\"og:description\" content=\"Welcome to this week\u2019s news roundup curated especially for non-silicon-based fans of AI. This week AI made a mayor speak in tongues. A two-day summit and $10m hopes to solve AI safety. And, ChatGPT will do whatever you ask if you show it the right pictures. Don\u2019t call us, AI will call you If you thought robocalls were bad before imagine what they could be like with a dash of AI. The FCC is trying to work out what to do about it. Meanwhile, the mayor of New York City just used deepfake tech to robocall city residents in a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dailyai.com\/de\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/\" \/>\n<meta property=\"og:site_name\" content=\"DailyAI\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-27T09:21:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-27T23:33:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/08\/Daily-AI-News-Weekly-Roundup.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"577\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eugene van der Watt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DailyAIOfficial\" \/>\n<meta name=\"twitter:site\" content=\"@DailyAIOfficial\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eugene van der Watt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2023\\\/10\\\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2023\\\/10\\\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\\\/\"},\"author\":{\"name\":\"Eugene van der Watt\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/person\\\/7ce525c6d0c79838b7cc7cde96993cfa\"},\"headline\":\"DAI#10 &#8211; Woodpeckers, Robocalls, and poisoned AI data\",\"datePublished\":\"2023-10-27T09:21:03+00:00\",\"dateModified\":\"2024-03-27T23:33:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2023\\\/10\\\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\\\/\"},\"wordCount\":1157,\"publisher\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2023\\\/10\\\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Daily-AI-News-Weekly-Roundup.jpg\",\"keywords\":[\"Roundup\"],\"articleSection\":{\"1\":\"Industry\"},\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2023\\\/10\\\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\\\/\",\"url\":\"https:\\\/\\\/dailyai.com\\\/2023\\\/10\\\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\\\/\",\"name\":\"DAI#10 - Woodpeckers, Robocalls, and poisoned AI data | DailyAI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2023\\\/10\\\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2023\\\/10\\\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Daily-AI-News-Weekly-Roundup.jpg\",\"datePublished\":\"2023-10-27T09:21:03+00:00\",\"dateModified\":\"2024-03-27T23:33:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2023\\\/10\\\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dailyai.com\\\/2023\\\/10\\\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2023\\\/10\\\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Daily-AI-News-Weekly-Roundup.jpg\",\"contentUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Daily-AI-News-Weekly-Roundup.jpg\",\"width\":1000,\"height\":577},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2023\\\/10\\\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dailyai.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DAI#10 &#8211; Woodpeckers, Robocalls, and poisoned AI data\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#website\",\"url\":\"https:\\\/\\\/dailyai.com\\\/\",\"name\":\"DailyAI\",\"description\":\"Your Daily Dose of AI News\",\"publisher\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dailyai.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#organization\",\"name\":\"DailyAI\",\"url\":\"https:\\\/\\\/dailyai.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Daily-Ai_TL_colour.png\",\"contentUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Daily-Ai_TL_colour.png\",\"width\":4501,\"height\":934,\"caption\":\"DailyAI\"},\"image\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/DailyAIOfficial\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dailyaiofficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@DailyAIOfficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/person\\\/7ce525c6d0c79838b7cc7cde96993cfa\",\"name\":\"Eugene van der Watt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Eugine_Profile_Picture-96x96.png\",\"url\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Eugine_Profile_Picture-96x96.png\",\"contentUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Eugine_Profile_Picture-96x96.png\",\"caption\":\"Eugene van der Watt\"},\"description\":\"Eugene comes from an electronic engineering background and loves all things tech. When he takes a break from consuming AI news you'll find him at the snooker table.\",\"sameAs\":[\"www.linkedin.com\\\/in\\\/eugene-van-der-watt-16828119\"],\"url\":\"https:\\\/\\\/dailyai.com\\\/de\\\/author\\\/eugene\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DAI#10 - Spechte, Robocalls und vergiftete KI-Daten | DailyAI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dailyai.com\/de\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/","og_locale":"de_DE","og_type":"article","og_title":"DAI#10 - Woodpeckers, Robocalls, and poisoned AI data | DailyAI","og_description":"Welcome to this week\u2019s news roundup curated especially for non-silicon-based fans of AI. This week AI made a mayor speak in tongues. A two-day summit and $10m hopes to solve AI safety. And, ChatGPT will do whatever you ask if you show it the right pictures. Don\u2019t call us, AI will call you If you thought robocalls were bad before imagine what they could be like with a dash of AI. The FCC is trying to work out what to do about it. Meanwhile, the mayor of New York City just used deepfake tech to robocall city residents in a","og_url":"https:\/\/dailyai.com\/de\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/","og_site_name":"DailyAI","article_published_time":"2023-10-27T09:21:03+00:00","article_modified_time":"2024-03-27T23:33:07+00:00","og_image":[{"width":1000,"height":577,"url":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/08\/Daily-AI-News-Weekly-Roundup.jpg","type":"image\/jpeg"}],"author":"Eugene van der Watt","twitter_card":"summary_large_image","twitter_creator":"@DailyAIOfficial","twitter_site":"@DailyAIOfficial","twitter_misc":{"Verfasst von":"Eugene van der Watt","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dailyai.com\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/#article","isPartOf":{"@id":"https:\/\/dailyai.com\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/"},"author":{"name":"Eugene van der Watt","@id":"https:\/\/dailyai.com\/#\/schema\/person\/7ce525c6d0c79838b7cc7cde96993cfa"},"headline":"DAI#10 &#8211; Woodpeckers, Robocalls, and poisoned AI data","datePublished":"2023-10-27T09:21:03+00:00","dateModified":"2024-03-27T23:33:07+00:00","mainEntityOfPage":{"@id":"https:\/\/dailyai.com\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/"},"wordCount":1157,"publisher":{"@id":"https:\/\/dailyai.com\/#organization"},"image":{"@id":"https:\/\/dailyai.com\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/#primaryimage"},"thumbnailUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/08\/Daily-AI-News-Weekly-Roundup.jpg","keywords":["Roundup"],"articleSection":{"1":"Industry"},"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/dailyai.com\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/","url":"https:\/\/dailyai.com\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/","name":"DAI#10 - Spechte, Robocalls und vergiftete KI-Daten | DailyAI","isPartOf":{"@id":"https:\/\/dailyai.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dailyai.com\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/#primaryimage"},"image":{"@id":"https:\/\/dailyai.com\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/#primaryimage"},"thumbnailUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/08\/Daily-AI-News-Weekly-Roundup.jpg","datePublished":"2023-10-27T09:21:03+00:00","dateModified":"2024-03-27T23:33:07+00:00","breadcrumb":{"@id":"https:\/\/dailyai.com\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dailyai.com\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dailyai.com\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/#primaryimage","url":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/08\/Daily-AI-News-Weekly-Roundup.jpg","contentUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/08\/Daily-AI-News-Weekly-Roundup.jpg","width":1000,"height":577},{"@type":"BreadcrumbList","@id":"https:\/\/dailyai.com\/2023\/10\/dai10-woodpeckers-robocalls-and-poisoned-ai-data\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dailyai.com\/"},{"@type":"ListItem","position":2,"name":"DAI#10 &#8211; Woodpeckers, Robocalls, and poisoned AI data"}]},{"@type":"WebSite","@id":"https:\/\/dailyai.com\/#website","url":"https:\/\/dailyai.com\/","name":"DailyAI","description":"Ihre t\u00e4gliche Dosis an AI-Nachrichten","publisher":{"@id":"https:\/\/dailyai.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dailyai.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dailyai.com\/#organization","name":"DailyAI","url":"https:\/\/dailyai.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dailyai.com\/#\/schema\/logo\/image\/","url":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/06\/Daily-Ai_TL_colour.png","contentUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/06\/Daily-Ai_TL_colour.png","width":4501,"height":934,"caption":"DailyAI"},"image":{"@id":"https:\/\/dailyai.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/DailyAIOfficial","https:\/\/www.linkedin.com\/company\/dailyaiofficial\/","https:\/\/www.youtube.com\/@DailyAIOfficial"]},{"@type":"Person","@id":"https:\/\/dailyai.com\/#\/schema\/person\/7ce525c6d0c79838b7cc7cde96993cfa","name":"Eugene van der Watt","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/Eugine_Profile_Picture-96x96.png","url":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/Eugine_Profile_Picture-96x96.png","contentUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/07\/Eugine_Profile_Picture-96x96.png","caption":"Eugene van der Watt"},"description":"Eugene kommt aus der Elektronikbranche und liebt alles, was mit Technik zu tun hat. Wenn er eine Pause vom Konsum von KI-Nachrichten einlegt, findet man ihn am Snookertisch.","sameAs":["www.linkedin.com\/in\/eugene-van-der-watt-16828119"],"url":"https:\/\/dailyai.com\/de\/author\/eugene\/"}]}},"_links":{"self":[{"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/posts\/6840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/comments?post=6840"}],"version-history":[{"count":7,"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/posts\/6840\/revisions"}],"predecessor-version":[{"id":6847,"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/posts\/6840\/revisions\/6847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/media\/3727"}],"wp:attachment":[{"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/media?parent=6840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/categories?post=6840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/tags?post=6840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}