{"id":10552,"date":"2024-03-06T19:15:27","date_gmt":"2024-03-06T19:15:27","guid":{"rendered":"https:\/\/dailyai.com\/?p=10552"},"modified":"2024-03-07T08:22:18","modified_gmt":"2024-03-07T08:22:18","slug":"the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics","status":"publish","type":"post","link":"https:\/\/dailyai.com\/de\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/","title":{"rendered":"Die US-Armee experimentiert mit GPT-4-gesteuerten Gefechtsfeldtaktiken"},"content":{"rendered":"<p><b>Die US-Armee versucht sich an der Integration von KI-Chatbots in ihre strategische Planung, allerdings im Rahmen einer Kriegsspielsimulation, die auf dem beliebten Videospiel Starcraft II basiert.\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Diese <\/span><a href=\"https:\/\/arxiv.org\/pdf\/2402.01786.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Studie<\/span><\/a><span style=\"font-weight: 400;\">unter der Leitung des US Army Research Laboratory, analysiert OpenAIs GPT-4 Turbo und GPT-4 Vision Schlachtfeldstrategien.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dies ist Teil von OpenAIs<\/span> <span style=\"font-weight: 400;\">Zusammenarbeit <a href=\"https:\/\/dailyai.com\/de\/2024\/01\/openai-says-its-ai-can-now-be-used-in-military-applications\/\">mit dem Verteidigungsministerium (DOD)<\/a> nach der Einrichtung des <a href=\"https:\/\/dailyai.com\/de\/2023\/08\/us-military-establishes-generative-ai-task-force\/\">Arbeitsgruppe f\u00fcr generative KI<\/a> letztes Jahr.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Der Einsatz von KI auf dem Schlachtfeld ist <\/span><a href=\"https:\/\/dailyai.com\/de\/2023\/08\/ai-on-the-battlefield-who-is-responsible-if-it-goes-wrong\/\"><span style=\"font-weight: 400;\">hei\u00df debattiert<\/span><\/a><span style=\"font-weight: 400;\">, mit einer <\/span><a href=\"https:\/\/dailyai.com\/de\/2024\/02\/ai-models-have-a-tendency-to-escalate-wargame-scenarios-says-study\/\"><span style=\"font-weight: 400;\">j\u00fcngste \u00e4hnliche Studie \u00fcber KI-Wargaming<\/span><\/a><span style=\"font-weight: 400;\"> die Feststellung, dass LLMs wie GPT-3.5 und GPT-4 dazu neigen, diplomatische Taktiken zu eskalieren, was manchmal zu einem Atomkrieg f\u00fchrt.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">In dieser neuen Studie der US-Armee wurde mit Starcraft II ein Gefechtsszenario mit einer begrenzten Anzahl von Milit\u00e4reinheiten simuliert.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die Forscher nannten dieses System \"COA-GPT\" - wobei COA f\u00fcr den milit\u00e4rischen Begriff \"Courses of Action\" steht, der im Wesentlichen milit\u00e4rische Taktiken beschreibt.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">COA-GPT \u00fcbernahm die Rolle eines Assistenten des milit\u00e4rischen Befehlshabers, der Strategien zur Vernichtung der gegnerischen Streitkr\u00e4fte und zur Einnahme strategischer Punkte entwickeln sollte.\u00a0<\/span><\/p>\n<figure id=\"attachment_10553\" aria-describedby=\"caption-attachment-10553\" style=\"width: 714px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10553\" src=\"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/diagram-1024x494.png\" alt=\"KI-Kriegsspiel\" width=\"714\" height=\"344\" srcset=\"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/diagram-1024x494.png 1024w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/diagram-300x145.png 300w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/diagram-768x370.png 768w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/diagram-18x9.png 18w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/diagram-370x178.png 370w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/diagram-800x386.png 800w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/diagram-740x357.png 740w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/diagram-20x10.png 20w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/diagram-100x48.png 100w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/diagram.png 1222w\" sizes=\"auto, (max-width: 714px) 100vw, 714px\" \/><figcaption id=\"caption-attachment-10553\" class=\"wp-caption-text\">COA-GPT ist ein KI-gest\u00fctztes System zur Entscheidungsunterst\u00fctzung, das das F\u00fchrungspersonal bei der Entwicklung von Handlungsoptionen (Courses of Action, COAs) unterst\u00fctzt. Es verwendet LLMs, die durch vordefinierte Richtlinien eingeschr\u00e4nkt sind. Das F\u00fchrungspersonal gibt Missionsinformationen ein und COA-GPT generiert potenzielle COAs. In einem iterativen Prozess, der nat\u00fcrliche Sprache verwendet, arbeiten die menschlichen Operatoren und COA-GPT zusammen, um die f\u00fcr die Missionsziele am besten geeigneten COAs zu verfeinern und auszuw\u00e4hlen. Quelle: <a href=\"https:\/\/arxiv.org\/pdf\/2402.01786.pdf\">ArXiv<\/a>.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">Die Forscher stellen fest, dass die herk\u00f6mmliche COA bekannterma\u00dfen langsam und arbeitsintensiv ist. COA-GPT trifft Entscheidungen innerhalb von Sekunden und integriert menschliches Feedback in den Lernprozess der KI.\u00a0<\/span><\/p>\n<figure id=\"attachment_10554\" aria-describedby=\"caption-attachment-10554\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10554 size-large\" src=\"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/wargame2-1024x373.png\" alt=\"Kriegsspiel AI\" width=\"1024\" height=\"373\" srcset=\"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/wargame2-1024x373.png 1024w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/wargame2-300x109.png 300w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/wargame2-768x280.png 768w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/wargame2-1536x560.png 1536w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/wargame2-18x7.png 18w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/wargame2-370x135.png 370w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/wargame2-800x291.png 800w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/wargame2-740x270.png 740w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/wargame2-20x7.png 20w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/wargame2-132x48.png 132w, https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/wargame2.png 1584w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-10554\" class=\"wp-caption-text\">Veranschaulicht den iterativen Prozess der Entwicklung von Aktionspl\u00e4nen (COAs) mit menschlichen Eingaben. In (a) generiert COA-GPT eine anf\u00e4ngliche COA ohne menschliche F\u00fchrung und zeigt Truppenbewegungen (blaue Pfeile) \u00fcber Br\u00fccken und Einsatzanweisungen (rote Pfeile) gegen feindliche Einheiten an. Panel (b) zeigt die COA, nachdem ein menschlicher Kommandant sie angepasst hat, indem er angibt, dass die eigenen Luftstreitkr\u00e4fte die feindlichen Luftstreitkr\u00e4fte direkt angreifen sollen. Schlie\u00dflich zeigt (c) eine weitere Verfeinerung der COA, wobei sich die Truppen aufteilen, um sowohl feindliche Artillerie als auch Aufkl\u00e4rungseinheiten zu bek\u00e4mpfen, die den Befehl erhalten, zur n\u00f6rdlichen Br\u00fccke vorzur\u00fccken. Quelle: <a href=\"https:\/\/arxiv.org\/pdf\/2402.01786.pdf\">ArXiv<\/a>.<\/figcaption><\/figure>\n<h2>COA-GPT \u00fcbertrifft andere Methoden, aber es ist mit Kosten verbunden<\/h2>\n<p><span style=\"font-weight: 400;\">COA-GPT zeigte eine bessere Leistung als die bestehenden Methoden und \u00fcbertraf die bestehenden Methoden bei der Erstellung strategischer COAs,<\/span><span style=\"font-weight: 400;\"> und k\u00f6nnte sich an Echtzeit-Feedback anpassen.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Allerdings gab es auch Schwachstellen. <\/span><span style=\"font-weight: 400;\">Vor allem COA-GPT hatte bei der Erf\u00fcllung der Missionsziele h\u00f6here Verluste zu beklagen. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">In der Studie hei\u00dft es: \"Wir stellen fest, dass COA-GPT und COA-GPT-V selbst dann, wenn sie mit menschlichem Feedback verbessert werden, im Vergleich zu anderen Grundmodellen h\u00f6here Verluste bei den eigenen Truppen aufweisen.\"<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Schreckt das die Forscher ab? Offensichtlich nicht. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">In der Studie hei\u00dft es: \"Zusammenfassend l\u00e4sst sich sagen, dass COA-GPT einen transformativen Ansatz f\u00fcr milit\u00e4rische C2-Operationen darstellt, der eine schnellere und agilere Entscheidungsfindung erm\u00f6glicht und einen strategischen Vorsprung in der modernen Kriegsf\u00fchrung sichert.\"<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es ist besorgniserregend, dass ein KI-System, das mehr unn\u00f6tige Opfer verursacht hat als die Basisversion, als \"transformativer Ansatz\" bezeichnet wird.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Das Verteidigungsministerium<\/span><span style=\"font-weight: 400;\"> hat bereits andere Wege zur Erforschung der milit\u00e4rischen Nutzung von KI aufgezeigt, aber es bestehen Bedenken hinsichtlich der Einsatzbereitschaft und der ethischen Auswirkungen der Technologie.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Wer ist zum Beispiel verantwortlich, wenn das Milit\u00e4r <\/span><a href=\"https:\/\/dailyai.com\/de\/2023\/08\/ai-on-the-battlefield-who-is-responsible-if-it-goes-wrong\/\"><span style=\"font-weight: 400;\">AI-Anwendungen gehen schief<\/span><\/a><span style=\"font-weight: 400;\">? Die Entwickler? Die verantwortliche Person? Oder jemand weiter unten in der Kette?<\/span><\/p>\n<p>KI-Kampff\u00fchrungssysteme werden bereits in den Konflikten in der Ukraine und in Pal\u00e4stina\/Israel eingesetzt, aber diese Fragen sind noch weitgehend unerprobt.<\/p>\n<p>Hoffen wir, dass es dabei bleibt.<\/p>","protected":false},"excerpt":{"rendered":"<p>Die US-Armee versucht sich an der Integration von KI-Chatbots in ihre strategische Planung, allerdings im Rahmen einer Kriegsspielsimulation, die auf dem beliebten Videospiel Starcraft II basiert.  Diese Studie, die vom US Army Research Laboratory geleitet wird, analysiert OpenAIs GPT-4 Turbo und GPT-4 Vision Schlachtfeldstrategien.  Die Studie ist Teil der Zusammenarbeit von OpenAI mit dem Verteidigungsministerium (DOD), das im vergangenen Jahr eine Task Force f\u00fcr generative KI gegr\u00fcndet hat.  Der Einsatz von KI auf dem Schlachtfeld wird heftig diskutiert. Eine k\u00fcrzlich durchgef\u00fchrte \u00e4hnliche Studie \u00fcber KI-Wargaming kam zu dem Ergebnis, dass LLMs wie GPT-3.5 und GPT-4 dazu neigen, diplomatische Taktiken zu eskalieren, manchmal<\/p>","protected":false},"author":2,"featured_media":10555,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[345],"class_list":["post-10552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ethics","tag-war"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The US Army experiments with GPT-4-controlled battlefield tactics | DailyAI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dailyai.com\/de\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The US Army experiments with GPT-4-controlled battlefield tactics | DailyAI\" \/>\n<meta property=\"og:description\" content=\"The US Army is dabbling with integrating AI chatbots into their strategic planning, albeit within the confines of a war game simulation based on the popular video game Starcraft II.\u00a0 This study, led by the US Army Research Laboratory, analyzes OpenAI&#8217;s GPT-4 Turbo and GPT-4 Vision battlefield strategies.\u00a0 This is part of OpenAI&#8217;s collaboration with the Department of Defense (DOD) following its establishment of the generative AI task force last year.\u00a0 AI\u2019s use on the battlefield is hotly debated, with a recent similar study on AI wargaming finding that LLMs like GPT-3.5 and GPT-4 tend to escalate diplomacy tactics, sometimes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dailyai.com\/de\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/\" \/>\n<meta property=\"og:site_name\" content=\"DailyAI\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-06T19:15:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T08:22:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/shutterstock_1424264186.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sam Jeans\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DailyAIOfficial\" \/>\n<meta name=\"twitter:site\" content=\"@DailyAIOfficial\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sam Jeans\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/03\\\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/03\\\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\\\/\"},\"author\":{\"name\":\"Sam Jeans\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/person\\\/711e81f945549438e8bbc579efdeb3c9\"},\"headline\":\"The US Army experiments with GPT-4-controlled battlefield tactics\",\"datePublished\":\"2024-03-06T19:15:27+00:00\",\"dateModified\":\"2024-03-07T08:22:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/03\\\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\\\/\"},\"wordCount\":566,\"publisher\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/03\\\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/shutterstock_1424264186.jpg\",\"keywords\":[\"War\"],\"articleSection\":[\"Ethics &amp; Society\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/03\\\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\\\/\",\"url\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/03\\\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\\\/\",\"name\":\"The US Army experiments with GPT-4-controlled battlefield tactics | DailyAI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/03\\\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/03\\\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/shutterstock_1424264186.jpg\",\"datePublished\":\"2024-03-06T19:15:27+00:00\",\"dateModified\":\"2024-03-07T08:22:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/03\\\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dailyai.com\\\/2024\\\/03\\\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/03\\\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/shutterstock_1424264186.jpg\",\"contentUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/shutterstock_1424264186.jpg\",\"width\":1000,\"height\":667,\"caption\":\"wargame AI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/2024\\\/03\\\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dailyai.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The US Army experiments with GPT-4-controlled battlefield tactics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#website\",\"url\":\"https:\\\/\\\/dailyai.com\\\/\",\"name\":\"DailyAI\",\"description\":\"Your Daily Dose of AI News\",\"publisher\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dailyai.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#organization\",\"name\":\"DailyAI\",\"url\":\"https:\\\/\\\/dailyai.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Daily-Ai_TL_colour.png\",\"contentUrl\":\"https:\\\/\\\/dailyai.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Daily-Ai_TL_colour.png\",\"width\":4501,\"height\":934,\"caption\":\"DailyAI\"},\"image\":{\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/DailyAIOfficial\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dailyaiofficial\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@DailyAIOfficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dailyai.com\\\/#\\\/schema\\\/person\\\/711e81f945549438e8bbc579efdeb3c9\",\"name\":\"Sam Jeans\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g\",\"caption\":\"Sam Jeans\"},\"description\":\"Sam is a science and technology writer who has worked in various AI startups. When he\u2019s not writing, he can be found reading medical journals or digging through boxes of vinyl records.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sam-jeans-6746b9142\\\/\"],\"url\":\"https:\\\/\\\/dailyai.com\\\/de\\\/author\\\/samjeans\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die US-Armee experimentiert mit GPT-4-gesteuerten Schlachtfeldtaktiken | DailyAI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dailyai.com\/de\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/","og_locale":"de_DE","og_type":"article","og_title":"The US Army experiments with GPT-4-controlled battlefield tactics | DailyAI","og_description":"The US Army is dabbling with integrating AI chatbots into their strategic planning, albeit within the confines of a war game simulation based on the popular video game Starcraft II.\u00a0 This study, led by the US Army Research Laboratory, analyzes OpenAI&#8217;s GPT-4 Turbo and GPT-4 Vision battlefield strategies.\u00a0 This is part of OpenAI&#8217;s collaboration with the Department of Defense (DOD) following its establishment of the generative AI task force last year.\u00a0 AI\u2019s use on the battlefield is hotly debated, with a recent similar study on AI wargaming finding that LLMs like GPT-3.5 and GPT-4 tend to escalate diplomacy tactics, sometimes","og_url":"https:\/\/dailyai.com\/de\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/","og_site_name":"DailyAI","article_published_time":"2024-03-06T19:15:27+00:00","article_modified_time":"2024-03-07T08:22:18+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/shutterstock_1424264186.jpg","type":"image\/jpeg"}],"author":"Sam Jeans","twitter_card":"summary_large_image","twitter_creator":"@DailyAIOfficial","twitter_site":"@DailyAIOfficial","twitter_misc":{"Verfasst von":"Sam Jeans","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dailyai.com\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/#article","isPartOf":{"@id":"https:\/\/dailyai.com\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/"},"author":{"name":"Sam Jeans","@id":"https:\/\/dailyai.com\/#\/schema\/person\/711e81f945549438e8bbc579efdeb3c9"},"headline":"The US Army experiments with GPT-4-controlled battlefield tactics","datePublished":"2024-03-06T19:15:27+00:00","dateModified":"2024-03-07T08:22:18+00:00","mainEntityOfPage":{"@id":"https:\/\/dailyai.com\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/"},"wordCount":566,"publisher":{"@id":"https:\/\/dailyai.com\/#organization"},"image":{"@id":"https:\/\/dailyai.com\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/#primaryimage"},"thumbnailUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/shutterstock_1424264186.jpg","keywords":["War"],"articleSection":["Ethics &amp; Society"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/dailyai.com\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/","url":"https:\/\/dailyai.com\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/","name":"Die US-Armee experimentiert mit GPT-4-gesteuerten Schlachtfeldtaktiken | DailyAI","isPartOf":{"@id":"https:\/\/dailyai.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dailyai.com\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/#primaryimage"},"image":{"@id":"https:\/\/dailyai.com\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/#primaryimage"},"thumbnailUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/shutterstock_1424264186.jpg","datePublished":"2024-03-06T19:15:27+00:00","dateModified":"2024-03-07T08:22:18+00:00","breadcrumb":{"@id":"https:\/\/dailyai.com\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dailyai.com\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dailyai.com\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/#primaryimage","url":"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/shutterstock_1424264186.jpg","contentUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2024\/03\/shutterstock_1424264186.jpg","width":1000,"height":667,"caption":"wargame AI"},{"@type":"BreadcrumbList","@id":"https:\/\/dailyai.com\/2024\/03\/the-us-army-experiments-with-gpt-4-controlled-battlefield-tactics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dailyai.com\/"},{"@type":"ListItem","position":2,"name":"The US Army experiments with GPT-4-controlled battlefield tactics"}]},{"@type":"WebSite","@id":"https:\/\/dailyai.com\/#website","url":"https:\/\/dailyai.com\/","name":"DailyAI","description":"Ihre t\u00e4gliche Dosis an AI-Nachrichten","publisher":{"@id":"https:\/\/dailyai.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dailyai.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dailyai.com\/#organization","name":"DailyAI","url":"https:\/\/dailyai.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dailyai.com\/#\/schema\/logo\/image\/","url":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/06\/Daily-Ai_TL_colour.png","contentUrl":"https:\/\/dailyai.com\/wp-content\/uploads\/2023\/06\/Daily-Ai_TL_colour.png","width":4501,"height":934,"caption":"DailyAI"},"image":{"@id":"https:\/\/dailyai.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/DailyAIOfficial","https:\/\/www.linkedin.com\/company\/dailyaiofficial\/","https:\/\/www.youtube.com\/@DailyAIOfficial"]},{"@type":"Person","@id":"https:\/\/dailyai.com\/#\/schema\/person\/711e81f945549438e8bbc579efdeb3c9","name":"Sam Jeans","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a24a4a8f8e2a1a275b7491dc9c9f032c401eabf23c3206da4628dc84b6dac5c8?s=96&d=robohash&r=g","caption":"Sam Jeans"},"description":"Sam ist ein Wissenschafts- und Technologiewissenschaftler, der in verschiedenen KI-Startups gearbeitet hat. Wenn er nicht gerade schreibt, liest er medizinische Fachzeitschriften oder kramt in Kisten mit Schallplatten.","sameAs":["https:\/\/www.linkedin.com\/in\/sam-jeans-6746b9142\/"],"url":"https:\/\/dailyai.com\/de\/author\/samjeans\/"}]}},"_links":{"self":[{"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/posts\/10552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/comments?post=10552"}],"version-history":[{"count":6,"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/posts\/10552\/revisions"}],"predecessor-version":[{"id":10562,"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/posts\/10552\/revisions\/10562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/media\/10555"}],"wp:attachment":[{"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/media?parent=10552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/categories?post=10552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyai.com\/de\/wp-json\/wp\/v2\/tags?post=10552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}